{"id":22663,"date":"2023-08-23T08:56:22","date_gmt":"2023-08-23T08:56:22","guid":{"rendered":"https:\/\/evolve-fitness.eu\/product\/evolve-prime-series-selectorized-horizontal-row-rangee-horizontale-selective\/"},"modified":"2026-04-23T10:04:55","modified_gmt":"2026-04-23T07:04:55","slug":"evolve-prime-series-selectorized-horizontal-row-rangee-horizontale-selective","status":"publish","type":"product","link":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-prime-series-selectorized-horizontal-row-rangee-horizontale-selective\/","title":{"rendered":"Evolve Prime Series Selectorized Horizontal Row (PR-202)"},"content":{"rendered":"\n<section class=\"wp-block-group alignfull has-lightgray-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-2edb0647 wp-block-columns-is-layout-flex\" style=\"margin-top:0;margin-bottom:0\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\"><\/div>\n<\/div>\n<\/section>\n\n<section class=\"wp-block-group alignfull black-content has-white-color has-darkgray-background-color has-text-color has-background is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--section-bottom);padding-bottom:var(--wp--preset--spacing--section-bottom)\">\n<section class=\"wp-block-group alignfull black-content has-white-color has-darkgray-background-color has-text-color has-background is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--section-bottom);padding-bottom:var(--wp--preset--spacing--section-bottom)\">\n<div class=\"wp-block-columns alignwide mobile-reverse is-layout-flex wp-container-core-columns-is-layout-ca64bf2d wp-block-columns-is-layout-flex\" style=\"margin-bottom:var(--wp--preset--spacing--side-padding)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\">R\u00e9volutionnez vos s\u00e9ances d&rsquo;entra\u00eenement<\/h3>\n\n\n\n<p><em><strong>Machines s\u00e9lectionn\u00e9es Evolve Prime Series<\/strong><\/em><\/p>\n\n\n\n<p style=\"margin-bottom:var(--wp--preset--spacing--tb-section-padding)\">Am\u00e9liorez votre parcours de remise en forme avec les appareils Selectorized de la s\u00e9rie Evolve Prime. Con\u00e7us pour des s\u00e9ances d&rsquo;entra\u00eenement efficaces, ces appareils offrent toute une s\u00e9rie de fonctions pour am\u00e9liorer votre routine d&rsquo;exercice. Gr\u00e2ce aux si\u00e8ges et aux dossiers r\u00e9glables, les utilisateurs peuvent personnaliser leur position d&rsquo;entra\u00eenement pour un maximum de confort. Les machines sont dot\u00e9es d&rsquo;un cadre ovale exceptionnellement durable, offrant \u00e0 la fois un design \u00e9l\u00e9gant et une long\u00e9vit\u00e9 adapt\u00e9e aux environnements commerciaux. Une base rembourr\u00e9e confortable assure la stabilit\u00e9 pendant vos s\u00e9ances d&rsquo;entra\u00eenement, tandis que les poign\u00e9es antid\u00e9rapantes, le design de la tour \u00e0 profil bas, la taille compacte et les couleurs personnalisables du cadre et du rembourrage ajoutent une touche de style \u00e0 votre salle de sport. D\u00e9couvrez les mouvements unilat\u00e9raux et les bras \u00e0 axes convergents qui offrent une exp\u00e9rience d&rsquo;entra\u00eenement naturelle et \u00e9quilibr\u00e9e.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\">L&rsquo;excellence ergonomique<\/h3>\n\n\n\n<p><strong><em>Adapt\u00e9 \u00e0 votre corps<\/em><\/strong><\/p>\n\n\n\n<p>Nos machines de musculation s\u00e9lectionn\u00e9es sont dot\u00e9es d&rsquo;une conception ergonomique qui s&rsquo;adapte \u00e0 l&rsquo;anatomie du corps humain. Cela permet de positionner correctement le corps et de stabiliser les articulations pendant l&rsquo;entra\u00eenement. Les poign\u00e9es sont recouvertes d&rsquo;un mat\u00e9riau antid\u00e9rapant, garantissant une stabilit\u00e9 maximale et la s\u00e9curit\u00e9 de l&rsquo;entra\u00eenement. Les si\u00e8ges et les dossiers r\u00e9glables permettent aux utilisateurs de trouver la position d&rsquo;entra\u00eenement id\u00e9ale pour r\u00e9pondre \u00e0 leurs besoins individuels. Les poign\u00e9es de r\u00e9glage, peintes en couleur vive, sont \u00e0 la fois faciles \u00e0 identifier et \u00e0 utiliser.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"1536\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3-4-edited.jpg\" alt=\"\" class=\"wp-image-2841\" style=\"width:684px;height:684px\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3-4-edited.jpg 1536w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3-4-edited-300x300.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3-4-edited-150x150.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3-4-edited-600x600.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3-4-edited-1024x1024.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3-4-edited-768x768.jpg 768w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-group alignfull black-content has-white-color has-darkgray-background-color has-text-color has-background is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--section-bottom);padding-bottom:var(--wp--preset--spacing--section-bottom)\">\n<div class=\"wp-block-columns alignwide mobile-reverse is-layout-flex wp-container-core-columns-is-layout-ca64bf2d wp-block-columns-is-layout-flex\" style=\"margin-bottom:var(--wp--preset--spacing--side-padding)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"767\" height=\"1024\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/13-2-767x1024.jpg\" alt=\"\" class=\"wp-image-2363\" style=\"width:594px;height:794px\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/13-2-767x1024.jpg 767w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/13-2-300x401.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/13-2-112x150.jpg 112w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/13-2-600x801.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/13-2-225x300.jpg 225w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/13-2-768x1026.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/13-2.jpg 864w\" sizes=\"auto, (max-width: 767px) 100vw, 767px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\">S\u00e9curit\u00e9 et simplicit\u00e9<\/h3>\n\n\n\n<p><strong><em>Ajustements sans effort<\/em><\/strong><\/p>\n\n\n\n<p style=\"margin-bottom:var(--wp--preset--spacing--tb-section-padding)\">La s\u00e9curit\u00e9 est primordiale, c&rsquo;est pourquoi les piles de poids de tous les appareils de musculation s\u00e9l\u00e9ctionn\u00e9s sont enti\u00e8rement recouvertes d&rsquo;un plastique opaque. Cela permet non seulement d&rsquo;am\u00e9liorer la s\u00e9curit\u00e9 de l&rsquo;entra\u00eenement, mais aussi d&rsquo;offrir un aspect attrayant. Le changement de r\u00e9sistance est un jeu d&rsquo;enfant &#8211; il suffit de glisser la goupille dans la pile de poids souhait\u00e9e. Chaque plaque de poids est prot\u00e9g\u00e9e par une couche suppl\u00e9mentaire r\u00e9sistante \u00e0 la corrosion.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\">Multi-fonctionnel<\/h3>\n\n\n\n<p><strong><em>La commodit\u00e9 au bout des doigts<\/em><\/strong><\/p>\n\n\n\n<p>Des compartiments de rangement int\u00e9gr\u00e9s permettent aux utilisateurs de garder \u00e0 port\u00e9e de main des objets essentiels comme des bouteilles d&rsquo;eau, des lecteurs de musique ou des t\u00e9l\u00e9phones portables. Des panneaux d&rsquo;information indiquent les groupes musculaires cibl\u00e9s par chaque entra\u00eeneur, et fournissent des conseils sur le positionnement du corps et les mouvements \u00e0 effectuer pour s&rsquo;assurer que les exercices sont ex\u00e9cut\u00e9s correctement. Les bras \u00e0 axe convergent imitent les mouvements naturels, et le mouvement unilat\u00e9ral des poign\u00e9es permet un engagement musculaire cibl\u00e9, que l&rsquo;on utilise une ou deux mains, ce qui favorise la force avec sym\u00e9trie et \u00e9quilibre.<\/p>\n<\/div>\n<\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-group alignfull black-content has-white-color has-darkgray-background-color has-text-color has-background is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--section-bottom);padding-bottom:var(--wp--preset--spacing--section-bottom)\">\n<div class=\"wp-block-columns alignwide mobile-reverse is-layout-flex wp-container-core-columns-is-layout-ca64bf2d wp-block-columns-is-layout-flex\" style=\"margin-bottom:var(--wp--preset--spacing--side-padding)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\">Confort somptueux<\/h3>\n\n\n\n<p><strong><em>Rembourrage de soutien<\/em><\/strong><\/p>\n\n\n\n<p style=\"margin-bottom:var(--wp--preset--spacing--tb-section-padding)\">La s\u00e9curit\u00e9 est primordiale, c&rsquo;est pourquoi les piles de poids de tous les appareils de musculation s\u00e9l\u00e9ctionn\u00e9s sont enti\u00e8rement recouvertes d&rsquo;un plastique opaque. Cela permet non seulement d&rsquo;am\u00e9liorer la s\u00e9curit\u00e9 de l&rsquo;entra\u00eenement, mais aussi d&rsquo;offrir un aspect attrayant. Le changement de r\u00e9sistance est un jeu d&rsquo;enfant &#8211; il suffit de glisser la goupille dans la pile de poids souhait\u00e9e. Chaque plaque de poids est prot\u00e9g\u00e9e par une couche suppl\u00e9mentaire r\u00e9sistante \u00e0 la corrosion.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\">Construit pour durer<\/h3>\n\n\n\n<p><strong><em>Cadre robuste<\/em><\/strong><\/p>\n\n\n\n<p>Fabriqu\u00e9 \u00e0 partir de tubes ovales soud\u00e9s et rev\u00eatus de poudre, le cadre est non seulement exceptionnellement durable, mais aussi r\u00e9sistant \u00e0 la rouille. Que vous soyez un particulier \u00e0 la recherche de qualit\u00e9 ou un gymnase professionnel ou un centre de remise en forme commercial, y compris les bases militaires, les h\u00f4tels, les auberges et les centres de r\u00e9\u00e9ducation, ces machines sont con\u00e7ues pour r\u00e9pondre \u00e0 vos attentes.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\">Id\u00e9al pour les professionnels<\/h3>\n\n\n\n<p><strong><em>Personnalisez votre salle de sport<\/em><\/strong><\/p>\n\n\n\n<p>Am\u00e9liorez l&rsquo;image de marque de votre salle de sport avec des \u00e9quipements qui correspondent \u00e0 votre style. Lorsque vous commandez un \u00e9quipement Evolve, nous l&rsquo;associons \u00e0 la palette de couleurs de votre int\u00e9rieur et personnalisons les couleurs du cadre et du rembourrage pour les adapter \u00e0 votre espace. D\u00e9couvrez la solution que vous attendiez &#8211; un \u00e9quipement de fitness adapt\u00e9 \u00e0 vos besoins. Choisissez des \u00e9quipements de fitness de haute qualit\u00e9 qui s&rsquo;int\u00e8grent parfaitement dans un environnement commercial tout en s&rsquo;harmonisant avec les couleurs de votre int\u00e9rieur.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"648\" height=\"864\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/33-edited.jpg\" alt=\"\" class=\"wp-image-2843\" style=\"width:572px;height:763px\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/33-edited.jpg 648w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/33-edited-300x400.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/33-edited-113x150.jpg 113w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/33-edited-600x800.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/33-edited-225x300.jpg 225w\" sizes=\"auto, (max-width: 648px) 100vw, 648px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/section>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Am\u00e9liorez votre entra\u00eenement de musculation avec le rameur horizontal Evolve Prime Series Selectorized, PR-202. Cette machine ergonomique offre pr\u00e9cision, s\u00e9curit\u00e9 et style. Dot\u00e9 de poign\u00e9es antid\u00e9rapantes, d&rsquo;un si\u00e8ge r\u00e9glable et d&rsquo;une pile de poids envelopp\u00e9e, il est parfait pour un d\u00e9veloppement musculaire \u00e9quilibr\u00e9. Avec ses rangements int\u00e9gr\u00e9s et son cadre durable, c&rsquo;est un choix id\u00e9al pour les environnements professionnels.<\/p>\n","protected":false},"featured_media":22768,"template":"","meta":{"_acf_changed":true,"inline_featured_image":false},"product_brand":[],"product_cat":[2681,2684],"product_tag":[],"class_list":{"0":"post-22663","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-machines-selectionnees","7":"product_cat-machines-selectorized-prime-series","9":"first","10":"instock","11":"virtual","12":"purchasable","13":"product-type-simple"},"acf":{"long_title":"Evolve Prime Series Selectorized Horizontal Row (PR-202)","subtitle":"","specifications":[{"label":"SKU","text_value":"EV-SC-PR-202","icon":"x"},{"label":"Dimensions","text_value":"1590 x 1115 x 1500 mm","icon":"x"},{"label":"Poids","text_value":"196 kg","icon":"x"},{"label":"Pile de poids","text_value":"114 kg","icon":"x"},{"label":"Plaque de poids sup\u00e9rieure","text_value":"2,25 kg","icon":"x"},{"label":"Poids maximal de l'utilisateur","text_value":"180 kg","icon":"x"},{"label":"Epaisseur du cadre","text_value":"3 mm","icon":"x"},{"label":"Autocollant d'instructions d'entra\u00eenement","text_value":"","icon":"v"},{"label":"Couche de protection suppl\u00e9mentaire","text_value":"","icon":"v"},{"label":"Position r\u00e9glable","text_value":"","icon":"v"},{"label":"Protecteurs de sol durables","text_value":"","icon":"v"},{"label":"Personnalisez les couleurs du cadre et du rev\u00eatement","text_value":"","icon":"v"},{"label":"Conception de la tour \u00e0 profil bas","text_value":"","icon":"v"},{"label":"Stockage int\u00e9gr\u00e9","text_value":"","icon":"v"},{"label":"Pile de poids envelopp\u00e9e","text_value":"","icon":"v"},{"label":"Mouvement ind\u00e9pendant du bras","text_value":"","icon":"v"},{"label":"Poign\u00e9es antid\u00e9rapantes avec rotation \u00e0 360","text_value":"","icon":"v"},{"label":"Goupille magn\u00e9tique d'empilage de poids","text_value":"","icon":"v"},{"label":"C\u00e2ble en nylon","text_value":"2 ans","icon":"v"},{"label":"Garantie  ","text_value":"2 ans","icon":"x"}],"product_frequently_asked_questions":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Evolve Prime Series Selectorized Horizontal Row (PR-202) - Evolve<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-prime-series-selectorized-horizontal-row-rangee-horizontale-selective\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evolve Prime Series Selectorized Horizontal Row (PR-202) - Evolve\" \/>\n<meta property=\"og:url\" content=\"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-prime-series-selectorized-horizontal-row-rangee-horizontale-selective\/\" \/>\n<meta property=\"og:site_name\" content=\"Evolve\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EvolveFitnessEurope\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-23T07:04:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/Evolve-Selectorized-PR-202.png\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-prime-series-selectorized-horizontal-row-rangee-horizontale-selective\\\/\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-prime-series-selectorized-horizontal-row-rangee-horizontale-selective\\\/\",\"name\":\"Evolve Prime Series Selectorized Horizontal Row (PR-202) - Evolve\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-prime-series-selectorized-horizontal-row-rangee-horizontale-selective\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-prime-series-selectorized-horizontal-row-rangee-horizontale-selective\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Evolve-Selectorized-PR-202.png\",\"datePublished\":\"2023-08-23T08:56:22+00:00\",\"dateModified\":\"2026-04-23T07:04:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-prime-series-selectorized-horizontal-row-rangee-horizontale-selective\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-prime-series-selectorized-horizontal-row-rangee-horizontale-selective\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-prime-series-selectorized-horizontal-row-rangee-horizontale-selective\\\/#primaryimage\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Evolve-Selectorized-PR-202.png\",\"contentUrl\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Evolve-Selectorized-PR-202.png\",\"width\":680,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-prime-series-selectorized-horizontal-row-rangee-horizontale-selective\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Evolve Prime Series Selectorized Horizontal Row (PR-202)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/\",\"name\":\"Evolve\",\"description\":\"Your Evolved Gear Arrived\",\"publisher\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#organization\",\"name\":\"Evolve\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Evolve-logo.svg\",\"contentUrl\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Evolve-logo.svg\",\"width\":176,\"height\":20,\"caption\":\"Evolve\"},\"image\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EvolveFitnessEurope\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Evolve Prime Series Selectorized Horizontal Row (PR-202) - Evolve","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-prime-series-selectorized-horizontal-row-rangee-horizontale-selective\/","og_locale":"fr_FR","og_type":"article","og_title":"Evolve Prime Series Selectorized Horizontal Row (PR-202) - Evolve","og_url":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-prime-series-selectorized-horizontal-row-rangee-horizontale-selective\/","og_site_name":"Evolve","article_publisher":"https:\/\/www.facebook.com\/EvolveFitnessEurope","article_modified_time":"2026-04-23T07:04:55+00:00","og_image":[{"width":680,"height":600,"url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/Evolve-Selectorized-PR-202.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-prime-series-selectorized-horizontal-row-rangee-horizontale-selective\/","url":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-prime-series-selectorized-horizontal-row-rangee-horizontale-selective\/","name":"Evolve Prime Series Selectorized Horizontal Row (PR-202) - Evolve","isPartOf":{"@id":"https:\/\/evolve-fitness.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-prime-series-selectorized-horizontal-row-rangee-horizontale-selective\/#primaryimage"},"image":{"@id":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-prime-series-selectorized-horizontal-row-rangee-horizontale-selective\/#primaryimage"},"thumbnailUrl":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/Evolve-Selectorized-PR-202.png","datePublished":"2023-08-23T08:56:22+00:00","dateModified":"2026-04-23T07:04:55+00:00","breadcrumb":{"@id":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-prime-series-selectorized-horizontal-row-rangee-horizontale-selective\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-prime-series-selectorized-horizontal-row-rangee-horizontale-selective\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-prime-series-selectorized-horizontal-row-rangee-horizontale-selective\/#primaryimage","url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/Evolve-Selectorized-PR-202.png","contentUrl":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/Evolve-Selectorized-PR-202.png","width":680,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-prime-series-selectorized-horizontal-row-rangee-horizontale-selective\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/evolve-fitness.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/evolve-fitness.eu\/fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Evolve Prime Series Selectorized Horizontal Row (PR-202)"}]},{"@type":"WebSite","@id":"https:\/\/evolve-fitness.eu\/fr\/#website","url":"https:\/\/evolve-fitness.eu\/fr\/","name":"Evolve","description":"Your Evolved Gear Arrived","publisher":{"@id":"https:\/\/evolve-fitness.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/evolve-fitness.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/evolve-fitness.eu\/fr\/#organization","name":"Evolve","url":"https:\/\/evolve-fitness.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/evolve-fitness.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/05\/Evolve-logo.svg","contentUrl":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/05\/Evolve-logo.svg","width":176,"height":20,"caption":"Evolve"},"image":{"@id":"https:\/\/evolve-fitness.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EvolveFitnessEurope"]}]}},"_links":{"self":[{"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/product\/22663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/media\/22768"}],"wp:attachment":[{"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/media?parent=22663"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/product_brand?post=22663"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/product_cat?post=22663"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/product_tag?post=22663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}