{"id":39159,"date":"2023-08-28T14:16:31","date_gmt":"2023-08-28T14:16:31","guid":{"rendered":"https:\/\/evolve-fitness.eu\/product\/evolve-econ-series-selectorized-stand-seat-abduction-abduction-du-siege\/"},"modified":"2024-12-06T13:34:52","modified_gmt":"2024-12-06T13:34:52","slug":"evolve-econ-series-selectorized-stand-seat-abduction-abduction-du-siege","status":"publish","type":"product","link":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-econ-series-selectorized-stand-seat-abduction-abduction-du-siege\/","title":{"rendered":"Evolve Econ Series Selectorized Stand \/ Seat Abduction (Abduction du si\u00e8ge)"},"content":{"rendered":"\n<section class=\"wp-block-group alignfull has-lightgray-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-2edb0647 wp-block-columns-is-layout-flex\" style=\"margin-top:0;margin-bottom:0\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\"><\/div>\n<\/div>\n<\/section>\n\n<section class=\"wp-block-group alignfull black-content has-white-color has-darkgray-background-color has-text-color has-background is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--section-bottom);padding-bottom:var(--wp--preset--spacing--section-bottom)\">\n<div class=\"wp-block-columns alignwide mobile-reverse is-layout-flex wp-container-core-columns-is-layout-ca64bf2d wp-block-columns-is-layout-flex\" style=\"margin-bottom:var(--wp--preset--spacing--side-padding)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\">S\u00e9rie Evolve Econ<\/h3>\n\n\n\n<p><em><strong><em><strong>L&rsquo;excellence \u00e0 un prix abordable<\/strong><\/em><\/strong><\/em><\/p>\n\n\n\n<p style=\"margin-bottom:var(--wp--preset--spacing--tb-section-padding)\">Bienvenue dans la s\u00e9rie Evolve Econ, o\u00f9 nous red\u00e9finissons l&rsquo;excellence sans nous ruiner. Con\u00e7ue pour les propri\u00e9taires de salles de sport, les propri\u00e9taires potentiels de salles de sport et les centres de remise en forme de toutes tailles, notre s\u00e9rie Econ propose une gamme d&rsquo;appareils s\u00e9lectifs \u00e9conomiques qui privil\u00e9gient la qualit\u00e9 et les performances. Examinons les caract\u00e9ristiques uniques qui font de la s\u00e9rie Econ un choix exceptionnel pour ceux qui recherchent un \u00e9quipement de fitness \u00e9conomique mais de haute qualit\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\">Durabilit\u00e9 et protection<\/h3>\n\n\n\n<p><strong><em><strong><em>L&rsquo;avantage des cadres \u00e0 rev\u00eatement en poudre<\/em><\/strong><\/em><\/strong><\/p>\n\n\n\n<p>D\u00e9couvrez la durabilit\u00e9 de nos \u00e9quipements gr\u00e2ce \u00e0 l&rsquo;avantage des cadres \u00e0 rev\u00eatement en poudre. R\u00e9sistants \u00e0 l&rsquo;\u00e9caillage et \u00e0 la rouille, ces cadres sont taill\u00e9s pour la long\u00e9vit\u00e9, garantissant ainsi que votre investissement r\u00e9sistera \u00e0 l&rsquo;\u00e9preuve du temps. Pour les propri\u00e9taires de salles de sport et les centres de remise en forme soucieux de leur budget, cette caract\u00e9ristique est essentielle pour fournir un \u00e9quipement qui dure sans grever le budget.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image alignright size-large is-resized is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/09\/Dizainas-be-pavadinimo-2-1024x1024.png\" alt=\"\" class=\"wp-image-4150\" style=\"object-fit:cover;width:680px;height:600px\" width=\"680\" height=\"600\"\/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-c45ee707 wp-block-columns-is-layout-flex\" style=\"margin-bottom:var(--wp--preset--spacing--side-padding);padding-top:var(--wp--preset--spacing--side-padding)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/09\/2655-edited.png\" alt=\"\" class=\"wp-image-4139\" style=\"object-fit:cover;width:660px;height:660px\" width=\"660\" height=\"660\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/09\/2655-edited.png 844w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/09\/2655-edited-300x300.png 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/09\/2655-edited-150x150.png 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/09\/2655-edited-600x600.png 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/09\/2655-edited-768x768.png 768w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\">La s\u00e9curit\u00e9 au service du style<\/h3>\n\n\n\n<p><strong><em><strong><em>Piles de poids envelopp\u00e9es<\/em><\/strong><\/em><\/strong><\/p>\n\n\n\n<p style=\"margin-bottom:var(--wp--preset--spacing--tb-section-padding)\">La s\u00e9rie Econ pr\u00e9sente une combinaison de s\u00e9curit\u00e9 et de style avec les piles de poids car\u00e9n\u00e9es. Les housses en plastique opaque donnent la priorit\u00e9 \u00e0 la s\u00e9curit\u00e9 de l&rsquo;entra\u00eenement tout en ajoutant une touche d&rsquo;\u00e9l\u00e9gance \u00e0 votre espace de remise en forme. Que vous soyez propri\u00e9taire d&rsquo;une salle de sport ou passionn\u00e9 de fitness, vous appr\u00e9cierez l&rsquo;attrait visuel et la s\u00e9curit\u00e9 que ces haubans apportent \u00e0 votre salle de sport.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\">Pr\u00e9servez votre espace<\/h3>\n\n\n\n<p><strong><em><strong><em>Coussinets en caoutchouc pour la protection des sols<\/em><\/strong><\/em><\/strong><\/p>\n\n\n\n<p>Maintenez un environnement d&rsquo;entra\u00eenement propre et sans d\u00e9g\u00e2ts gr\u00e2ce aux tampons en caoutchouc. Les propri\u00e9taires de salles de sport sont conscients de l&rsquo;importance de pr\u00e9server leurs sols. Nos pieds rev\u00eatus de caoutchouc prot\u00e8gent votre sol contre les rayures et les dommages potentiels, ce qui fait de la s\u00e9rie Econ un choix rentable pour les propri\u00e9taires de salles de sport qui souhaitent prot\u00e9ger leur espace.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center mobile-reverse is-layout-flex wp-container-core-columns-is-layout-e8158c2f wp-block-columns-is-layout-flex\" style=\"padding-top:var(--wp--preset--spacing--side-padding)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\">Une commodit\u00e9 intelligente<\/h3>\n\n\n\n<p><strong><em>Rangement int\u00e9gr\u00e9 pour les s\u00e9ances d&rsquo;entra\u00eenement modernes<\/em><\/strong><\/p>\n\n\n\n<p style=\"margin-bottom:var(--wp--preset--spacing--tb-section-padding)\">Dans le paysage actuel de la remise en forme, la commodit\u00e9 est importante. Notre rangement int\u00e9gr\u00e9 permet aux propri\u00e9taires de salles de sport et aux adeptes du fitness de garder bouteilles d&rsquo;eau, t\u00e9l\u00e9phones portables et autres accessoires \u00e0 port\u00e9e de main. Il s&rsquo;agit d&rsquo;une fonction modeste mais efficace, con\u00e7ue pour r\u00e9pondre aux besoins modernes de vos clients en mati\u00e8re de remise en forme.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\">Confiance et stabilit\u00e9<\/h3>\n\n\n\n<p><strong><em>Poign\u00e9es antid\u00e9rapantes pour des s\u00e9ances d&rsquo;entra\u00eenement en toute s\u00e9curit\u00e9<\/em><\/strong><\/p>\n\n\n\n<p>Les poign\u00e9es antid\u00e9rapantes donnent la priorit\u00e9 \u00e0 la s\u00e9curit\u00e9 et \u00e0 la stabilit\u00e9 de l&rsquo;entra\u00eenement. Les propri\u00e9taires de salles de sport et les responsables d&rsquo;\u00e9tablissements de remise en forme comprennent l&rsquo;importance d&rsquo;un \u00e9quipement qui inspire la confiance. Nos poign\u00e9es sont recouvertes d&rsquo;un mat\u00e9riau antid\u00e9rapant, offrant aux utilisateurs l&rsquo;assurance dont ils ont besoin pendant leurs s\u00e9ances d&rsquo;entra\u00eenement.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image alignright size-full is-resized is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/09\/3-edited.png\" alt=\"\" class=\"wp-image-4143\" style=\"width:665px;height:665px\" width=\"665\" height=\"665\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/09\/3-edited.png 808w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/09\/3-edited-300x300.png 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/09\/3-edited-150x150.png 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/09\/3-edited-600x600.png 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/09\/3-edited-768x768.png 768w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center mobile-reverse is-layout-flex wp-container-core-columns-is-layout-e8158c2f wp-block-columns-is-layout-flex\" style=\"padding-top:var(--wp--preset--spacing--side-padding)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image alignright size-full is-resized is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/09\/4-2.jpg\" alt=\"\" class=\"wp-image-4154\" style=\"width:665px;height:665px\" width=\"665\" height=\"665\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/09\/4-2.jpg 945w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/09\/4-2-300x300.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/09\/4-2-150x150.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/09\/4-2-600x600.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/09\/4-2-768x768.jpg 768w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\">Un confort durable<\/h3>\n\n\n\n<p><strong><em><strong><em>Rembourrage robuste pour les passionn\u00e9s de fitness<\/em><\/strong><\/em><\/strong><\/p>\n\n\n\n<p style=\"margin-bottom:var(--wp--preset--spacing--tb-section-padding)\">Profitez d&rsquo;un confort durable gr\u00e2ce \u00e0 notre rembourrage robuste. Confortable et r\u00e9sistant, il s&rsquo;adapte \u00e0 la forme du corps de l&rsquo;utilisateur, garantissant que chaque s\u00e9ance d&rsquo;entra\u00eenement est non seulement rentable mais aussi confortable. Les propri\u00e9taires de salles de sport peuvent offrir \u00e0 leurs clients une exp\u00e9rience d&rsquo;entra\u00eenement confortable qui les incite \u00e0 revenir.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\">Options polyvalentes<\/h3>\n\n\n\n<p><strong><em><strong><em>Armes de l&rsquo;axe convergent et mouvement unilat\u00e9ral <\/em><\/strong><em>(Disponible sur certaines machines)<\/em><\/em><\/strong><\/p>\n\n\n\n<p>Profitez d&rsquo;un confort durable gr\u00e2ce \u00e0 notre rembourrage robuste. Confortable et r\u00e9sistant, il s&rsquo;adapte \u00e0 la forme du corps de l&rsquo;utilisateur, garantissant que chaque s\u00e9ance d&rsquo;entra\u00eenement est non seulement rentable mais aussi confortable. Les propri\u00e9taires de salles de sport peuvent offrir \u00e0 leurs clients une exp\u00e9rience d&rsquo;entra\u00eenement confortable qui les incite \u00e0 revenir.<\/p>\n<\/div>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;appareil de musculation Evolve Econ Abduction permet de r\u00e9aliser des s\u00e9ances d&rsquo;entra\u00eenement efficaces. Sa conception ergonomique, ses fonctions r\u00e9glables et sa capacit\u00e9 de charge de 100 kg offrent une exp\u00e9rience de remise en forme sur mesure. Le cadre durable, les poign\u00e9es antid\u00e9rapantes et le rangement int\u00e9gr\u00e9 en font un outil id\u00e9al pour tous les environnements. Am\u00e9liorez votre routine gr\u00e2ce \u00e0 cet \u00e9quipement polyvalent.<\/p>\n","protected":false},"featured_media":39160,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[2681,3544],"product_tag":[],"class_list":{"0":"post-39159","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-machines-selectionnees","7":"product_cat-machines-selectorized-econ-series","9":"first","10":"instock","11":"virtual","12":"purchasable","13":"product-type-simple"},"acf":{"long_title":"Evolve Econ Series Selectorized Stand \/ Seat Abduction, EC-036","subtitle":"","specifications":[{"label":"SKU","text_value":"EV-SC-EC-036","icon":"x"},{"label":"Dimensions","text_value":"1627 x 689 x 1575 mm","icon":"x"},{"label":"Poids","text_value":"125 kg (sans les piles de poids)","icon":"x"},{"label":"Poids maximal de l'utilisateur","text_value":"180 kg","icon":"x"},{"label":"Pile de poids","text_value":"100 kg","icon":"x"},{"label":"Autocollant d'instructions d'entra\u00eenement","text_value":"","icon":"v"},{"label":"Rouleaux r\u00e9glables pour les coussins des jambes","text_value":"","icon":"v"},{"label":"Protecteurs de sol durables","text_value":"","icon":"v"},{"label":"Pile de poids envelopp\u00e9e","text_value":"","icon":"v"},{"label":"Stockage int\u00e9gr\u00e9","text_value":"","icon":"v"},{"label":"Garantie  ","text_value":"2 ans","icon":"x"}],"product_frequently_asked_questions":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Evolve Econ Series Selectorized Stand \/ Seat Abduction (Abduction du si\u00e8ge) - Evolve<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-econ-series-selectorized-stand-seat-abduction-abduction-du-siege\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evolve Econ Series Selectorized Stand \/ Seat Abduction (Abduction du si\u00e8ge) - Evolve\" \/>\n<meta property=\"og:url\" content=\"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-econ-series-selectorized-stand-seat-abduction-abduction-du-siege\/\" \/>\n<meta property=\"og:site_name\" content=\"Evolve\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EvolveFitnessEurope\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-06T13:34:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/Evolve-Selectorized-EC-036.png\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-econ-series-selectorized-stand-seat-abduction-abduction-du-siege\\\/\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-econ-series-selectorized-stand-seat-abduction-abduction-du-siege\\\/\",\"name\":\"Evolve Econ Series Selectorized Stand \\\/ Seat Abduction (Abduction du si\u00e8ge) - Evolve\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-econ-series-selectorized-stand-seat-abduction-abduction-du-siege\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-econ-series-selectorized-stand-seat-abduction-abduction-du-siege\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Evolve-Selectorized-EC-036.png\",\"datePublished\":\"2023-08-28T14:16:31+00:00\",\"dateModified\":\"2024-12-06T13:34:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-econ-series-selectorized-stand-seat-abduction-abduction-du-siege\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-econ-series-selectorized-stand-seat-abduction-abduction-du-siege\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-econ-series-selectorized-stand-seat-abduction-abduction-du-siege\\\/#primaryimage\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Evolve-Selectorized-EC-036.png\",\"contentUrl\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Evolve-Selectorized-EC-036.png\",\"width\":680,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-econ-series-selectorized-stand-seat-abduction-abduction-du-siege\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Evolve Econ Series Selectorized Stand \\\/ Seat Abduction (Abduction du si\u00e8ge)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/\",\"name\":\"Evolve\",\"description\":\"Your Evolved Gear Arrived\",\"publisher\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#organization\",\"name\":\"Evolve\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Evolve-logo.svg\",\"contentUrl\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Evolve-logo.svg\",\"width\":176,\"height\":20,\"caption\":\"Evolve\"},\"image\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EvolveFitnessEurope\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Evolve Econ Series Selectorized Stand \/ Seat Abduction (Abduction du si\u00e8ge) - Evolve","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-econ-series-selectorized-stand-seat-abduction-abduction-du-siege\/","og_locale":"fr_FR","og_type":"article","og_title":"Evolve Econ Series Selectorized Stand \/ Seat Abduction (Abduction du si\u00e8ge) - Evolve","og_url":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-econ-series-selectorized-stand-seat-abduction-abduction-du-siege\/","og_site_name":"Evolve","article_publisher":"https:\/\/www.facebook.com\/EvolveFitnessEurope","article_modified_time":"2024-12-06T13:34:52+00:00","og_image":[{"width":680,"height":600,"url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/Evolve-Selectorized-EC-036.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-econ-series-selectorized-stand-seat-abduction-abduction-du-siege\/","url":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-econ-series-selectorized-stand-seat-abduction-abduction-du-siege\/","name":"Evolve Econ Series Selectorized Stand \/ Seat Abduction (Abduction du si\u00e8ge) - Evolve","isPartOf":{"@id":"https:\/\/evolve-fitness.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-econ-series-selectorized-stand-seat-abduction-abduction-du-siege\/#primaryimage"},"image":{"@id":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-econ-series-selectorized-stand-seat-abduction-abduction-du-siege\/#primaryimage"},"thumbnailUrl":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/Evolve-Selectorized-EC-036.png","datePublished":"2023-08-28T14:16:31+00:00","dateModified":"2024-12-06T13:34:52+00:00","breadcrumb":{"@id":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-econ-series-selectorized-stand-seat-abduction-abduction-du-siege\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-econ-series-selectorized-stand-seat-abduction-abduction-du-siege\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-econ-series-selectorized-stand-seat-abduction-abduction-du-siege\/#primaryimage","url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/Evolve-Selectorized-EC-036.png","contentUrl":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/Evolve-Selectorized-EC-036.png","width":680,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-econ-series-selectorized-stand-seat-abduction-abduction-du-siege\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/evolve-fitness.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/evolve-fitness.eu\/fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Evolve Econ Series Selectorized Stand \/ Seat Abduction (Abduction du si\u00e8ge)"}]},{"@type":"WebSite","@id":"https:\/\/evolve-fitness.eu\/fr\/#website","url":"https:\/\/evolve-fitness.eu\/fr\/","name":"Evolve","description":"Your Evolved Gear Arrived","publisher":{"@id":"https:\/\/evolve-fitness.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/evolve-fitness.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/evolve-fitness.eu\/fr\/#organization","name":"Evolve","url":"https:\/\/evolve-fitness.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/evolve-fitness.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/05\/Evolve-logo.svg","contentUrl":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/05\/Evolve-logo.svg","width":176,"height":20,"caption":"Evolve"},"image":{"@id":"https:\/\/evolve-fitness.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EvolveFitnessEurope"]}]}},"_links":{"self":[{"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/product\/39159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/media\/39160"}],"wp:attachment":[{"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/media?parent=39159"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/product_brand?post=39159"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/product_cat?post=39159"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/product_tag?post=39159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}