{"id":72596,"date":"2023-12-27T10:44:59","date_gmt":"2023-12-27T10:44:59","guid":{"rendered":"https:\/\/evolve-fitness.eu\/product\/evolve-digital-strength-series-selectorized-leg-extension-leg-curl-extension-et-flexion-des-jambes\/"},"modified":"2024-11-19T11:56:05","modified_gmt":"2024-11-19T11:56:05","slug":"evolve-digital-strength-series-selectorized-leg-extension-leg-curl-extension-et-flexion-des-jambes","status":"publish","type":"product","link":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-digital-strength-series-selectorized-leg-extension-leg-curl-extension-et-flexion-des-jambes\/","title":{"rendered":"Evolve Digital Strength Series Selectorized Leg Extension &amp; Leg Curl (Extension et flexion des jambes)"},"content":{"rendered":"\n<section class=\"wp-block-group alignfull has-lightgray-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-2edb0647 wp-block-columns-is-layout-flex\" style=\"margin-top:0;margin-bottom:0\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\"><\/div>\n<\/div>\n<\/section>\n\n<section class=\"wp-block-group alignfull black-content has-white-color has-darkgray-background-color has-text-color has-background is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--section-bottom);padding-bottom:var(--wp--preset--spacing--section-bottom)\">\n<div class=\"wp-block-columns alignwide mobile-reverse is-layout-flex wp-container-core-columns-is-layout-ca64bf2d wp-block-columns-is-layout-flex\" style=\"margin-bottom:var(--wp--preset--spacing--side-padding)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\">introduction<\/h3>\n\n\n\n<p><strong><em><strong><em><strong><strong><strong><strong><strong><strong>Bienvenue dans la pr\u00e9sentation de la nouvelle g\u00e9n\u00e9ration d&rsquo;\u00e9quipements GYM<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/em><\/strong><\/em><\/strong><\/p>\n\n\n\n<p style=\"margin-bottom:var(--wp--preset--spacing--tb-section-padding)\">D\u00e9couvrez les caract\u00e9ristiques innovantes de la s\u00e9rie Evolve DIGITAL dans notre derni\u00e8re pr\u00e9sentation vid\u00e9o. Nous nous penchons sur les aspects uniques de cet appareil de pointe pour la presse \u00e0 pectoraux et \u00e0 \u00e9paules, en pr\u00e9sentant son interface num\u00e9rique, sa r\u00e9sistance r\u00e9glable, son design ergonomique et sa construction robuste. Pour une exp\u00e9rience vraiment immersive, <strong>nous recommandons de couper le son<\/strong>.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-video\"><video height=\"2160\" style=\"aspect-ratio: 3840 \/ 2160;\" width=\"3840\" autoplay=\"\" controls=\"\" loop=\"\" muted=\"\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/Digital-Strength-Line-Chest-Press-1-minute-LQ.mp4\"><\/video><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-c45ee707 wp-block-columns-is-layout-flex\" style=\"margin-bottom:var(--wp--preset--spacing--side-padding);padding-top:var(--wp--preset--spacing--side-padding)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-video\"><video height=\"720\" style=\"aspect-ratio: 1280 \/ 720;\" width=\"1280\" autoplay=\"\" controls=\"\" loop=\"\" muted=\"\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2024\/06\/EV-SC-DS-425-360CAM.mp4\"><\/video><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\"><strong><strong><strong><strong><em>Caract\u00e9ristiques principales<\/em><\/strong><\/strong><\/strong><\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L&rsquo;accoudoir r\u00e9glable permet aux utilisateurs d&rsquo;adapter la machine \u00e0 une position optimale.<\/li>\n\n\n\n<li>Le support des pieds offre confort et stabilit\u00e9 pour les s\u00e9ances d&rsquo;entra\u00eenement.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-c45ee707 wp-block-columns-is-layout-flex\" style=\"margin-bottom:var(--wp--preset--spacing--side-padding);padding-top:var(--wp--preset--spacing--side-padding)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\">R\u00e9sistance num\u00e9rique adaptative<\/h3>\n\n\n\n<p><strong><em>Le moteur \u00e9lectrique fournit une r\u00e9sistance num\u00e9rique stable<\/em><\/strong><\/p>\n\n\n\n<p style=\"margin-bottom:var(--wp--preset--spacing--tb-section-padding)\">L&rsquo;\u00e9quipement de gymnastique num\u00e9rique Evolve int\u00e8gre des moteurs \u00e9lectriques avanc\u00e9s qui font partie int\u00e9grante de sa conception de pointe. Ces moteurs sont con\u00e7us pour \u00eatre efficaces, durables et fonctionner en douceur, garantissant ainsi une exp\u00e9rience d&rsquo;entra\u00eenement sans faille. Ils utilisent des algorithmes et des capteurs sophistiqu\u00e9s pour ajuster automatiquement les niveaux de r\u00e9sistance, en fonction des besoins sp\u00e9cifiques et des progr\u00e8s de l&rsquo;utilisateur. Cette adaptabilit\u00e9 rend l&rsquo;\u00e9quipement polyvalent, convenant \u00e0 une large gamme d&rsquo;exercices, des mouvements de r\u00e9\u00e9ducation doux aux exercices de musculation intenses. En outre, les moteurs sont con\u00e7us pour \u00eatre efficaces sur le plan \u00e9nerg\u00e9tique, ce qui contribue au caract\u00e8re \u00e9cologique de l&rsquo;\u00e9quipement. L&rsquo;int\u00e9gration de ces moteurs \u00e9lectriques \u00e0 des interfaces num\u00e9riques permet aux utilisateurs de suivre leurs performances, de se fixer des objectifs et de recevoir des recommandations d&rsquo;entra\u00eenement personnalis\u00e9es, ce qui fait de l&rsquo;\u00e9quipement de gymnastique Evolve un produit phare dans le domaine de la technologie du fitness.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/motor.png\" alt=\"\" class=\"wp-image-9077\"\/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-c45ee707 wp-block-columns-is-layout-flex\" style=\"margin-bottom:var(--wp--preset--spacing--side-padding);padding-top:var(--wp--preset--spacing--side-padding)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05146-1024x683.jpg\" alt=\"\" class=\"wp-image-8962\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05146-1024x683.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05146-300x200.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05146-scaled-225x150.jpg 225w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05146-scaled-600x400.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05146-150x100.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05146-768x512.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05146-1536x1024.jpg 1536w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05146-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\"><strong><strong><strong>Interface num\u00e9rique<\/strong><\/strong><\/strong><\/h3>\n\n\n\n<p><strong><em>La s\u00e9rie Evolve DIGITAL est dot\u00e9e d&rsquo;une interface num\u00e9rique avanc\u00e9e.<\/em><\/strong><\/p>\n\n\n\n<p style=\"margin-bottom:var(--wp--preset--spacing--tb-section-padding)\">L&rsquo;\u00e9cran fournit des informations en temps r\u00e9el sur votre entra\u00eenement. Cette interface affiche des mesures cl\u00e9s telles que les r\u00e9p\u00e9titions, la dur\u00e9e des s\u00e9ries et l&rsquo;engagement musculaire, ce qui vous permet de suivre vos progr\u00e8s et d&rsquo;ajuster votre entra\u00eenement pour une efficacit\u00e9 maximale. La conception conviviale permet aux d\u00e9butants comme aux utilisateurs exp\u00e9riment\u00e9s de naviguer facilement et d&rsquo;utiliser cette fonction pour une exp\u00e9rience d&rsquo;exercice optimis\u00e9e.<\/p>\n\n\n\n<p><strong><em>R\u00e9glage de la r\u00e9sistance et flexibilit\u00e9 comme aucun autre appareil<\/em><\/strong><\/p>\n\n\n\n<p style=\"margin-bottom:var(--wp--preset--spacing--tb-section-padding)\">S&rsquo;adressant \u00e0 un large \u00e9ventail de niveaux de condition physique, l&rsquo;appareil offre des niveaux de r\u00e9sistance r\u00e9glables. Cette flexibilit\u00e9 permet aux utilisateurs d&rsquo;augmenter progressivement l&rsquo;intensit\u00e9 de leur entra\u00eenement, ce qui en fait un outil id\u00e9al pour l&rsquo;entra\u00eenement progressif de la force. Le m\u00e9canisme de r\u00e9glage transparent assure une transition en douceur entre les diff\u00e9rents niveaux de r\u00e9sistance, ce qui permet aux utilisateurs de se concentrer sur leur forme et leur technique sans interruption.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-c45ee707 wp-block-columns-is-layout-flex\" style=\"margin-bottom:var(--wp--preset--spacing--side-padding);padding-top:var(--wp--preset--spacing--side-padding)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Mode d&rsquo;entra\u00eenement<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong> &#8211; Standard<\/h3>\n\n\n\n<p><strong><em>Poids concentrique = Poids excentrique<\/em><\/strong><\/p>\n\n\n\n<p style=\"margin-bottom:var(--wp--preset--spacing--tb-section-padding)\">Il s&rsquo;agit du mode traditionnel dans lequel la r\u00e9sistance reste constante tout au long de l&rsquo;exercice, offrant un d\u00e9fi r\u00e9gulier et uniforme.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05151-1024x683.jpg\" alt=\"\" class=\"wp-image-8973\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05151-1024x683.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05151-300x200.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05151-scaled-225x150.jpg 225w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05151-scaled-600x400.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05151-150x100.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05151-768x512.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05151-1536x1024.jpg 1536w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05151-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-c45ee707 wp-block-columns-is-layout-flex\" style=\"margin-bottom:var(--wp--preset--spacing--side-padding);padding-top:var(--wp--preset--spacing--side-padding)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05153-1-1024x683.jpg\" alt=\"\" class=\"wp-image-8975\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05153-1-1024x683.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05153-1-300x200.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05153-1-scaled-225x150.jpg 225w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05153-1-scaled-600x400.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05153-1-150x100.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05153-1-768x512.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05153-1-1536x1024.jpg 1536w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05153-1-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Mode d&rsquo;entra\u00eenement<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong> &#8211; <\/strong><\/strong><\/strong><\/strong>excentrique<\/h3>\n\n\n\n<p><strong><em>Poids concentrique &lt; Poids excentrique<\/em><\/strong><\/p>\n\n\n\n<p style=\"margin-bottom:var(--wp--preset--spacing--tb-section-padding)\">Dans ce mode, la r\u00e9sistance augmente pendant la phase excentrique (descente) de l&rsquo;exercice, ce qui favorise le renforcement et la croissance musculaire en se concentrant sur l&rsquo;allongement du muscle. Les muscles sont davantage stimul\u00e9s et la croissance musculaire est plus efficace.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-c45ee707 wp-block-columns-is-layout-flex\" style=\"margin-bottom:var(--wp--preset--spacing--side-padding);padding-top:var(--wp--preset--spacing--side-padding)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Mode d&rsquo;entra\u00eenement<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong> &#8211;  <\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong>isocin\u00e9tique<\/h3>\n\n\n\n<p><strong><em>Vitesse = R\u00e9sistance<\/em><\/strong><\/p>\n\n\n\n<p style=\"margin-bottom:var(--wp--preset--spacing--tb-section-padding)\">Ce mode maintient la vitesse du mouvement constante, quelle que soit la force appliqu\u00e9e. Il est particuli\u00e8rement utile pour la r\u00e9\u00e9ducation et pour assurer une activation musculaire contr\u00f4l\u00e9e.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05154-1024x683.jpg\" alt=\"\" class=\"wp-image-8977\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05154-1024x683.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05154-300x200.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05154-scaled-225x150.jpg 225w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05154-scaled-600x400.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05154-150x100.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05154-768x512.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05154-1536x1024.jpg 1536w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05154-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-c45ee707 wp-block-columns-is-layout-flex\" style=\"margin-bottom:var(--wp--preset--spacing--side-padding);padding-top:var(--wp--preset--spacing--side-padding)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05156-1024x683.jpg\" alt=\"\" class=\"wp-image-8979\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05156-1024x683.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05156-300x200.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05156-scaled-225x150.jpg 225w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05156-scaled-600x400.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05156-150x100.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05156-768x512.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05156-1536x1024.jpg 1536w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/A7_05156-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Mode d&rsquo;entra\u00eenement<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong> &#8211; <\/strong><\/strong><\/strong><\/strong>\u00e9lastique<\/h3>\n\n\n\n<p><strong><em>Cordon &gt; R\u00e9sistance<\/em><\/strong><\/p>\n\n\n\n<p style=\"margin-bottom:var(--wp--preset--spacing--tb-section-padding)\">Plus la corde de traction est longue, plus la r\u00e9sistance est importante. Ce mode simule l&rsquo;exp\u00e9rience de la r\u00e9sistance \u00e9lastique, comme si vous travailliez avec des bandes de r\u00e9sistance, offrant un d\u00e9fi unique et une variabilit\u00e9 de l&rsquo;entra\u00eenement. Plus efficace pour l&rsquo;entra\u00eenement explosif.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-c45ee707 wp-block-columns-is-layout-flex\" style=\"margin-bottom:var(--wp--preset--spacing--side-padding);padding-top:var(--wp--preset--spacing--side-padding)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\"><strong><strong><strong><strong>Conception ergonomique<\/strong><\/strong><\/strong><\/strong><\/h3>\n\n\n\n<p><strong><em>La conception ergonomique donne la priorit\u00e9 au confort et \u00e0 la s\u00e9curit\u00e9 de l&rsquo;utilisateur.<\/em><\/strong><\/p>\n\n\n\n<p style=\"margin-bottom:var(--wp--preset--spacing--tb-section-padding)\">L&rsquo;\u00e9quipement est con\u00e7u pour s&rsquo;aligner sur les mouvements naturels du corps, r\u00e9duisant ainsi le risque de blessure et garantissant un engagement musculaire efficace. Les si\u00e8ges profil\u00e9s et les poign\u00e9es strat\u00e9giquement plac\u00e9es am\u00e9liorent la stabilit\u00e9 et le contr\u00f4le pendant l&rsquo;entra\u00eenement, ce qui en fait un choix confortable et s\u00fbr pour tous les utilisateurs.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/EV-SC-DS-425-2-1024x683.jpg\" alt=\"\" class=\"wp-image-159535\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/EV-SC-DS-425-2-1024x683.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/EV-SC-DS-425-2-300x200.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/EV-SC-DS-425-2-150x100.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/EV-SC-DS-425-2-768x512.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/EV-SC-DS-425-2-1536x1024.jpg 1536w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/EV-SC-DS-425-2-2048x1365.jpg 2048w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/EV-SC-DS-425-2-600x400.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/EV-SC-DS-425-2-225x150.jpg 225w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-c45ee707 wp-block-columns-is-layout-flex\" style=\"margin-bottom:var(--wp--preset--spacing--side-padding);padding-top:var(--wp--preset--spacing--side-padding)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/EV-SC-DS-425-4-683x1024.jpg\" alt=\"\" class=\"wp-image-159510\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/EV-SC-DS-425-4-683x1024.jpg 683w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/EV-SC-DS-425-4-200x300.jpg 200w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/EV-SC-DS-425-4-100x150.jpg 100w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/EV-SC-DS-425-4-768x1152.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/EV-SC-DS-425-4-1024x1536.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/EV-SC-DS-425-4-1365x2048.jpg 1365w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/EV-SC-DS-425-4-300x450.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/EV-SC-DS-425-4-600x900.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/EV-SC-DS-425-4.jpg 1373w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--h-3-bottom)\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Construction robuste<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h3>\n\n\n\n<p><strong><em>Con\u00e7u pour r\u00e9sister aux rigueurs des s\u00e9ances d&rsquo;entra\u00eenement intenses<\/em><\/strong><\/p>\n\n\n\n<p style=\"margin-bottom:var(--wp--preset--spacing--tb-section-padding)\">Des mat\u00e9riaux de haute qualit\u00e9 et une construction robuste garantissent une durabilit\u00e9 et une fiabilit\u00e9 \u00e0 long terme. Cette conception garantit non seulement la s\u00e9curit\u00e9 des utilisateurs, mais aussi des performances constantes dans le temps, ce qui en fait un investissement pr\u00e9cieux pour les salles de sport et les centres de remise en forme professionnels.<\/p>\n<\/div>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00e9quipement de pointe Evolve combine un design robuste et l&rsquo;innovation num\u00e9rique pour offrir une exp\u00e9rience d&rsquo;entra\u00eenement in\u00e9gal\u00e9e. Sa biom\u00e9canique avanc\u00e9e garantit un engagement musculaire optimal, tandis que l&rsquo;interface num\u00e9rique fournit un retour d&rsquo;information en temps r\u00e9el pour suivre vos progr\u00e8s. Id\u00e9al pour les d\u00e9butants et les athl\u00e8tes chevronn\u00e9s. Il permet une gamme d&rsquo;exercices pour cibler et renforcer les muscles de la poitrine et des \u00e9paules comme aucun autre \u00e9quipement. D\u00e9couvrez le m\u00e9lange parfait de technologie et de performance avec l&rsquo;Evolve DIGITAL SERIES, votre partenaire pour atteindre une condition physique optimale.<\/p>\n","protected":false},"featured_media":134632,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[3644,2681],"product_tag":[],"class_list":{"0":"post-72596","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-machines-a-selection-de-force-numerique","7":"product_cat-machines-selectionnees","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":{"long_title":"Evolve Digital Strength Series Selectorized Leg Extension & Leg Curl (Extension et flexion des jambes)","subtitle":"","specifications":[{"label":"SKU","text_value":"EV-SC-DS-425","icon":"x"},{"label":"Pr\u00e9cision de l'ajustement","text_value":"1 kg","icon":"x"},{"label":"M\u00e9thode d'ajustement","text_value":"\u00c9cran tactile","icon":"x"},{"label":"Taille de l'\u00e9cran","text_value":"10,1 pouces","icon":"x"},{"label":"Test de r\u00e9sistance","text_value":"AI","icon":"x"},{"label":"Mode d'entra\u00eenement","text_value":"Standart\/Eccentrique\/Isokin\u00e9tique\/Elastique","icon":"x"},{"label":"Donn\u00e9es d'entra\u00eenement","text_value":"Enregistrement automatique des donn\u00e9es de processus\/r\u00e9sultats","icon":"x"},{"label":"R\u00e9sistance minimale","text_value":"5 kg","icon":"x"},{"label":"R\u00e9sistance maximale","text_value":"100 kg","icon":"x"},{"label":"MEAS","text_value":"1440 x 1320 x 1170","icon":"x"},{"label":"Poids maximal de l'utilisateur","text_value":"180 kg","icon":"x"},{"label":"","text_value":"","icon":"x"},{"label":"","text_value":"","icon":"x"},{"label":"","text_value":"","icon":"x"},{"label":"","text_value":"","icon":"x"},{"label":"","text_value":"","icon":"x"},{"label":"Garantie","text_value":"2 ans","icon":"x"},{"label":"","text_value":"","icon":"x"},{"label":"","text_value":"","icon":"v"},{"label":"","text_value":"","icon":"v"},{"label":"","text_value":"","icon":"x"}],"product_frequently_asked_questions":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Evolve Digital Strength Series Selectorized Leg Extension &amp; Leg Curl (Extension et flexion des jambes) - Evolve<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-digital-strength-series-selectorized-leg-extension-leg-curl-extension-et-flexion-des-jambes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evolve Digital Strength Series Selectorized Leg Extension &amp; Leg Curl (Extension et flexion des jambes) - Evolve\" \/>\n<meta property=\"og:url\" content=\"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-digital-strength-series-selectorized-leg-extension-leg-curl-extension-et-flexion-des-jambes\/\" \/>\n<meta property=\"og:site_name\" content=\"Evolve\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EvolveFitnessEurope\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-19T11:56:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/MAIN-EV-SC-DS-425-Evolve-Digital-Strength-Series-Selectorized-Leg-Extension-Leg-Curl-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-digital-strength-series-selectorized-leg-extension-leg-curl-extension-et-flexion-des-jambes\\\/\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-digital-strength-series-selectorized-leg-extension-leg-curl-extension-et-flexion-des-jambes\\\/\",\"name\":\"Evolve Digital Strength Series Selectorized Leg Extension &amp; Leg Curl (Extension et flexion des jambes) - Evolve\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-digital-strength-series-selectorized-leg-extension-leg-curl-extension-et-flexion-des-jambes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-digital-strength-series-selectorized-leg-extension-leg-curl-extension-et-flexion-des-jambes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/MAIN-EV-SC-DS-425-Evolve-Digital-Strength-Series-Selectorized-Leg-Extension-Leg-Curl-1.png\",\"datePublished\":\"2023-12-27T10:44:59+00:00\",\"dateModified\":\"2024-11-19T11:56:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-digital-strength-series-selectorized-leg-extension-leg-curl-extension-et-flexion-des-jambes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-digital-strength-series-selectorized-leg-extension-leg-curl-extension-et-flexion-des-jambes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-digital-strength-series-selectorized-leg-extension-leg-curl-extension-et-flexion-des-jambes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/MAIN-EV-SC-DS-425-Evolve-Digital-Strength-Series-Selectorized-Leg-Extension-Leg-Curl-1.png\",\"contentUrl\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/MAIN-EV-SC-DS-425-Evolve-Digital-Strength-Series-Selectorized-Leg-Extension-Leg-Curl-1.png\",\"width\":680,\"height\":600,\"caption\":\"EV-SC-DS-425\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/produit\\\/evolve-digital-strength-series-selectorized-leg-extension-leg-curl-extension-et-flexion-des-jambes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Evolve Digital Strength Series Selectorized Leg Extension &amp; Leg Curl (Extension et flexion des jambes)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/\",\"name\":\"Evolve\",\"description\":\"Your Evolved Gear Arrived\",\"publisher\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#organization\",\"name\":\"Evolve\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Evolve-logo.svg\",\"contentUrl\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Evolve-logo.svg\",\"width\":176,\"height\":20,\"caption\":\"Evolve\"},\"image\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EvolveFitnessEurope\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Evolve Digital Strength Series Selectorized Leg Extension &amp; Leg Curl (Extension et flexion des jambes) - Evolve","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-digital-strength-series-selectorized-leg-extension-leg-curl-extension-et-flexion-des-jambes\/","og_locale":"fr_FR","og_type":"article","og_title":"Evolve Digital Strength Series Selectorized Leg Extension &amp; Leg Curl (Extension et flexion des jambes) - Evolve","og_url":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-digital-strength-series-selectorized-leg-extension-leg-curl-extension-et-flexion-des-jambes\/","og_site_name":"Evolve","article_publisher":"https:\/\/www.facebook.com\/EvolveFitnessEurope","article_modified_time":"2024-11-19T11:56:05+00:00","og_image":[{"width":680,"height":600,"url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/MAIN-EV-SC-DS-425-Evolve-Digital-Strength-Series-Selectorized-Leg-Extension-Leg-Curl-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-digital-strength-series-selectorized-leg-extension-leg-curl-extension-et-flexion-des-jambes\/","url":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-digital-strength-series-selectorized-leg-extension-leg-curl-extension-et-flexion-des-jambes\/","name":"Evolve Digital Strength Series Selectorized Leg Extension &amp; Leg Curl (Extension et flexion des jambes) - Evolve","isPartOf":{"@id":"https:\/\/evolve-fitness.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-digital-strength-series-selectorized-leg-extension-leg-curl-extension-et-flexion-des-jambes\/#primaryimage"},"image":{"@id":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-digital-strength-series-selectorized-leg-extension-leg-curl-extension-et-flexion-des-jambes\/#primaryimage"},"thumbnailUrl":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/MAIN-EV-SC-DS-425-Evolve-Digital-Strength-Series-Selectorized-Leg-Extension-Leg-Curl-1.png","datePublished":"2023-12-27T10:44:59+00:00","dateModified":"2024-11-19T11:56:05+00:00","breadcrumb":{"@id":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-digital-strength-series-selectorized-leg-extension-leg-curl-extension-et-flexion-des-jambes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-digital-strength-series-selectorized-leg-extension-leg-curl-extension-et-flexion-des-jambes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-digital-strength-series-selectorized-leg-extension-leg-curl-extension-et-flexion-des-jambes\/#primaryimage","url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/MAIN-EV-SC-DS-425-Evolve-Digital-Strength-Series-Selectorized-Leg-Extension-Leg-Curl-1.png","contentUrl":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/12\/MAIN-EV-SC-DS-425-Evolve-Digital-Strength-Series-Selectorized-Leg-Extension-Leg-Curl-1.png","width":680,"height":600,"caption":"EV-SC-DS-425"},{"@type":"BreadcrumbList","@id":"https:\/\/evolve-fitness.eu\/fr\/produit\/evolve-digital-strength-series-selectorized-leg-extension-leg-curl-extension-et-flexion-des-jambes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/evolve-fitness.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/evolve-fitness.eu\/fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Evolve Digital Strength Series Selectorized Leg Extension &amp; Leg Curl (Extension et flexion des jambes)"}]},{"@type":"WebSite","@id":"https:\/\/evolve-fitness.eu\/fr\/#website","url":"https:\/\/evolve-fitness.eu\/fr\/","name":"Evolve","description":"Your Evolved Gear Arrived","publisher":{"@id":"https:\/\/evolve-fitness.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/evolve-fitness.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/evolve-fitness.eu\/fr\/#organization","name":"Evolve","url":"https:\/\/evolve-fitness.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/evolve-fitness.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/05\/Evolve-logo.svg","contentUrl":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/05\/Evolve-logo.svg","width":176,"height":20,"caption":"Evolve"},"image":{"@id":"https:\/\/evolve-fitness.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EvolveFitnessEurope"]}]}},"_links":{"self":[{"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/product\/72596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/media\/134632"}],"wp:attachment":[{"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/media?parent=72596"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/product_brand?post=72596"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/product_cat?post=72596"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/product_tag?post=72596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}