{"id":1415,"count":13,"description":"Nos bancs de fitness allient durabilit\u00e9 et fonctionnalit\u00e9. Fabriqu\u00e9s avec un cadre m\u00e9tallique robuste et un rev\u00eatement antirouille avanc\u00e9, ces bancs sont parfaits pour les particuliers, les salles de sport professionnelles et les centres de remise en forme commerciaux. Dot\u00e9s de rev\u00eatements en PVC prot\u00e9geant le sol, d'une conception stable pour les exercices sur l'ensemble du corps et d'un rembourrage en mousse confortable et r\u00e9sistant \u00e0 la d\u00e9formation, recouvert de cuir PU de qualit\u00e9 sup\u00e9rieure, ces bancs red\u00e9finissent votre exp\u00e9rience de l'entra\u00eenement.","link":"https:\/\/evolve-fitness.eu\/fr\/categorie-produit\/bancs\/bancs-econ-series\/","name":"Bancs Econ Series\u2122","slug":"bancs-econ-series","taxonomy":"product_cat","parent":1414,"meta":[],"menu_order":21,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bancs Econ Series\u2122 Archives - Evolve<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/evolve-fitness.eu\/fr\/categorie-produit\/bancs\/bancs-econ-series\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bancs Econ Series\u2122 Archives - Evolve\" \/>\n<meta property=\"og:description\" content=\"Nos bancs de fitness allient durabilit\u00e9 et fonctionnalit\u00e9. Fabriqu\u00e9s avec un cadre m\u00e9tallique robuste et un rev\u00eatement antirouille avanc\u00e9, ces bancs sont parfaits pour les particuliers, les salles de sport professionnelles et les centres de remise en forme commerciaux. Dot\u00e9s de rev\u00eatements en PVC prot\u00e9geant le sol, d&rsquo;une conception stable pour les exercices sur l&rsquo;ensemble du corps et d&rsquo;un rembourrage en mousse confortable et r\u00e9sistant \u00e0 la d\u00e9formation, recouvert de cuir PU de qualit\u00e9 sup\u00e9rieure, ces bancs red\u00e9finissent votre exp\u00e9rience de l&rsquo;entra\u00eenement.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/evolve-fitness.eu\/fr\/categorie-produit\/bancs\/bancs-econ-series\/\" \/>\n<meta property=\"og:site_name\" content=\"Evolve\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/categorie-produit\\\/bancs\\\/bancs-econ-series\\\/\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/categorie-produit\\\/bancs\\\/bancs-econ-series\\\/\",\"name\":\"Bancs Econ Series\u2122 Archives - Evolve\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/categorie-produit\\\/bancs\\\/bancs-econ-series\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/categorie-produit\\\/bancs\\\/bancs-econ-series\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bancs\",\"item\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/categorie-produit\\\/bancs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bancs Econ Series\u2122\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/\",\"name\":\"Evolve\",\"description\":\"Your Evolved Gear Arrived\",\"publisher\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#organization\",\"name\":\"Evolve\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Evolve-logo.svg\",\"contentUrl\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Evolve-logo.svg\",\"width\":176,\"height\":20,\"caption\":\"Evolve\"},\"image\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EvolveFitnessEurope\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bancs Econ Series\u2122 Archives - Evolve","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/evolve-fitness.eu\/fr\/categorie-produit\/bancs\/bancs-econ-series\/","og_locale":"fr_FR","og_type":"article","og_title":"Bancs Econ Series\u2122 Archives - Evolve","og_description":"Nos bancs de fitness allient durabilit\u00e9 et fonctionnalit\u00e9. Fabriqu\u00e9s avec un cadre m\u00e9tallique robuste et un rev\u00eatement antirouille avanc\u00e9, ces bancs sont parfaits pour les particuliers, les salles de sport professionnelles et les centres de remise en forme commerciaux. Dot\u00e9s de rev\u00eatements en PVC prot\u00e9geant le sol, d&rsquo;une conception stable pour les exercices sur l&rsquo;ensemble du corps et d&rsquo;un rembourrage en mousse confortable et r\u00e9sistant \u00e0 la d\u00e9formation, recouvert de cuir PU de qualit\u00e9 sup\u00e9rieure, ces bancs red\u00e9finissent votre exp\u00e9rience de l&rsquo;entra\u00eenement.","og_url":"https:\/\/evolve-fitness.eu\/fr\/categorie-produit\/bancs\/bancs-econ-series\/","og_site_name":"Evolve","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/evolve-fitness.eu\/fr\/categorie-produit\/bancs\/bancs-econ-series\/","url":"https:\/\/evolve-fitness.eu\/fr\/categorie-produit\/bancs\/bancs-econ-series\/","name":"Bancs Econ Series\u2122 Archives - Evolve","isPartOf":{"@id":"https:\/\/evolve-fitness.eu\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/evolve-fitness.eu\/fr\/categorie-produit\/bancs\/bancs-econ-series\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/evolve-fitness.eu\/fr\/categorie-produit\/bancs\/bancs-econ-series\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/evolve-fitness.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Bancs","item":"https:\/\/evolve-fitness.eu\/fr\/categorie-produit\/bancs\/"},{"@type":"ListItem","position":3,"name":"Bancs Econ Series\u2122"}]},{"@type":"WebSite","@id":"https:\/\/evolve-fitness.eu\/fr\/#website","url":"https:\/\/evolve-fitness.eu\/fr\/","name":"Evolve","description":"Your Evolved Gear Arrived","publisher":{"@id":"https:\/\/evolve-fitness.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/evolve-fitness.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/evolve-fitness.eu\/fr\/#organization","name":"Evolve","url":"https:\/\/evolve-fitness.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/evolve-fitness.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/05\/Evolve-logo.svg","contentUrl":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/05\/Evolve-logo.svg","width":176,"height":20,"caption":"Evolve"},"image":{"@id":"https:\/\/evolve-fitness.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EvolveFitnessEurope"]}]}},"_links":{"self":[{"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/product_cat\/1415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/product_cat\/1414"}],"wp:post_type":[{"href":"https:\/\/evolve-fitness.eu\/fr\/wp-json\/wp\/v2\/product?product_cat=1415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}