{"id":15826,"date":"2023-11-18T13:14:52","date_gmt":"2023-11-18T13:14:52","guid":{"rendered":"https:\/\/evolve-fitness.eu\/project\/sporto-sale-2\/"},"modified":"2026-04-23T08:42:11","modified_gmt":"2026-04-23T05:42:11","slug":"sporto-sale-2","status":"publish","type":"project","link":"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-2\/","title":{"rendered":"Gym+ Klaip\u0117da Vingis"},"content":{"rendered":"\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-top:var(--wp--preset--spacing--section-top);padding-bottom:var(--wp--preset--spacing--section-top);flex-basis:100%\">\n<h3 class=\"wp-block-heading alignwide\" style=\"margin-top:0;margin-bottom:var(--wp--preset--spacing--section-title-bottom)\">Projekt\u0173 galerija<\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-4 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1.4-1024x575.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" data-id=\"1931\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1.4-1024x575.jpg\" alt=\"\" class=\"wp-image-1931\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1.4-1024x575.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1.4-300x169.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1.4-267x150.jpg 267w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1.4-600x337.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1.4-150x84.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1.4-768x432.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1.4.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1.5-1024x767.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"767\" data-id=\"1928\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1.5-1024x767.jpg\" alt=\"\" class=\"wp-image-1928\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1.5-1024x767.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1.5-300x225.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1.5-200x150.jpg 200w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1.5-600x449.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1.5-150x112.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1.5-768x575.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1.5.jpg 1154w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2.4-1024x576.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"1934\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2.4-1024x576.jpg\" alt=\"\" class=\"wp-image-1934\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2.4-1024x576.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2.4-300x169.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2.4-267x150.jpg 267w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2.4-600x338.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2.4-150x84.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2.4-768x432.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2.4.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2-3-1024x767.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"767\" data-id=\"1938\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2-3-1024x767.jpg\" alt=\"\" class=\"wp-image-1938\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2-3-1024x767.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2-3-300x225.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2-3-200x150.jpg 200w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2-3-600x449.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2-3-150x112.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2-3-768x575.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2-3.jpg 1154w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3.4-1024x576.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"1940\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3.4-1024x576.jpg\" alt=\"\" class=\"wp-image-1940\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3.4-1024x576.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3.4-300x169.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3.4-267x150.jpg 267w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3.4-600x338.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3.4-150x84.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3.4-768x432.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3.4.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3.5-1024x767.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"767\" data-id=\"1941\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3.5-1024x767.jpg\" alt=\"\" class=\"wp-image-1941\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3.5-1024x767.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3.5-300x225.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3.5-200x150.jpg 200w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3.5-600x449.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3.5-150x112.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3.5-768x575.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3.5.jpg 1154w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/7.4-1024x575.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" data-id=\"1944\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/7.4-1024x575.jpg\" alt=\"\" class=\"wp-image-1944\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/7.4-1024x575.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/7.4-300x169.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/7.4-267x150.jpg 267w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/7.4-600x337.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/7.4-150x84.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/7.4-768x432.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/7.4.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/8.4-1024x576.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"1949\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/8.4-1024x576.jpg\" alt=\"\" class=\"wp-image-1949\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/8.4-1024x576.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/8.4-300x169.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/8.4-267x150.jpg 267w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/8.4-600x338.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/8.4-150x84.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/8.4-768x432.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/8.4.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/10.4-1024x575.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" data-id=\"1950\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/10.4-1024x575.jpg\" alt=\"\" class=\"wp-image-1950\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/10.4-1024x575.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/10.4-300x169.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/10.4-267x150.jpg 267w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/10.4-600x337.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/10.4-150x84.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/10.4-768x432.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/10.4.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/11.4.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" data-id=\"1948\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/11.4-1024x575.jpg\" alt=\"\" class=\"wp-image-1948\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/11.4-1024x575.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/11.4-300x169.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/11.4-267x150.jpg 267w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/11.4-600x337.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/11.4-150x84.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/11.4-768x432.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/11.4.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/14.4-1024x575.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" data-id=\"1955\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/14.4-1024x575.jpg\" alt=\"\" class=\"wp-image-1955\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/14.4-1024x575.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/14.4-300x169.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/14.4-267x150.jpg 267w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/14.4-600x337.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/14.4-150x84.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/14.4-768x432.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/14.4.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/15.4-1024x575.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" data-id=\"1957\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/15.4-1024x575.jpg\" alt=\"\" class=\"wp-image-1957\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/15.4-1024x575.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/15.4-300x169.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/15.4-267x150.jpg 267w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/15.4-600x337.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/15.4-150x84.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/15.4-768x432.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/15.4.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/17.3-1024x575.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" data-id=\"1960\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/17.3-1024x575.jpg\" alt=\"\" class=\"wp-image-1960\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/17.3-1024x575.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/17.3-300x169.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/17.3-267x150.jpg 267w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/17.3-600x337.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/17.3-150x84.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/17.3-768x432.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/17.3.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/19.3-1024x575.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" data-id=\"1963\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/19.3-1024x575.jpg\" alt=\"\" class=\"wp-image-1963\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/19.3-1024x575.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/19.3-300x169.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/19.3-267x150.jpg 267w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/19.3-600x337.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/19.3-150x84.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/19.3-768x432.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/19.3.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/20.3-1024x575.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" data-id=\"1959\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/20.3-1024x575.jpg\" alt=\"\" class=\"wp-image-1959\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/20.3-1024x575.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/20.3-300x169.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/20.3-267x150.jpg 267w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/20.3-600x337.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/20.3-150x84.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/20.3-768x432.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/20.3.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/23.2-1024x575.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" data-id=\"1965\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/23.2-1024x575.jpg\" alt=\"\" class=\"wp-image-1965\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/23.2-1024x575.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/23.2-300x169.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/23.2-267x150.jpg 267w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/23.2-600x337.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/23.2-150x84.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/23.2-768x432.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/23.2.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/24.2-1024x575.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" data-id=\"1967\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/24.2-1024x575.jpg\" alt=\"\" class=\"wp-image-1967\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/24.2-1024x575.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/24.2-300x169.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/24.2-267x150.jpg 267w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/24.2-600x337.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/24.2-150x84.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/24.2-768x432.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/24.2.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/25.2-1024x575.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" data-id=\"1970\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/25.2-1024x575.jpg\" alt=\"\" class=\"wp-image-1970\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/25.2-1024x575.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/25.2-300x169.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/25.2-267x150.jpg 267w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/25.2-600x337.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/25.2-150x84.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/25.2-768x432.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/25.2.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/26.2-576x1024.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" data-id=\"1969\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/26.2-576x1024.jpg\" alt=\"\" class=\"wp-image-1969\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/26.2-576x1024.jpg 576w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/26.2-300x533.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/26.2-84x150.jpg 84w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/26.2-600x1066.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/26.2-169x300.jpg 169w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/26.2-768x1365.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/26.2.jpg 844w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2024\/06\/182399143_2851180468488593_3221986043299596779_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"139301\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2024\/06\/182399143_2851180468488593_3221986043299596779_n-1024x683.jpg\" alt=\"\" class=\"wp-image-139301\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2024\/06\/182399143_2851180468488593_3221986043299596779_n-1024x683.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2024\/06\/182399143_2851180468488593_3221986043299596779_n-300x200.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2024\/06\/182399143_2851180468488593_3221986043299596779_n-225x150.jpg 225w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2024\/06\/182399143_2851180468488593_3221986043299596779_n-600x400.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2024\/06\/182399143_2851180468488593_3221986043299596779_n-150x100.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2024\/06\/182399143_2851180468488593_3221986043299596779_n-768x512.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2024\/06\/182399143_2851180468488593_3221986043299596779_n-1536x1024.jpg 1536w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2024\/06\/182399143_2851180468488593_3221986043299596779_n.jpg 1837w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/41.1-1024x575.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" data-id=\"1975\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/41.1-1024x575.jpg\" alt=\"\" class=\"wp-image-1975\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/41.1-1024x575.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/41.1-300x169.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/41.1-267x150.jpg 267w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/41.1-600x337.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/41.1-150x84.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/41.1-768x432.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/41.1.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/42.1-1024x575.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" data-id=\"1977\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/42.1-1024x575.jpg\" alt=\"\" class=\"wp-image-1977\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/42.1-1024x575.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/42.1-300x169.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/42.1-267x150.jpg 267w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/42.1-600x337.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/42.1-150x84.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/42.1-768x432.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/42.1.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/43.1-576x1024.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" data-id=\"1978\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/43.1-576x1024.jpg\" alt=\"\" class=\"wp-image-1978\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/43.1-576x1024.jpg 576w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/43.1-300x533.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/43.1-84x150.jpg 84w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/43.1-600x1066.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/43.1-169x300.jpg 169w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/43.1-768x1365.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/43.1.jpg 844w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/47-576x1024.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" data-id=\"1988\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/47-576x1024.jpg\" alt=\"\" class=\"wp-image-1988\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/47-576x1024.jpg 576w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/47-300x533.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/47-84x150.jpg 84w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/47-600x1066.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/47-169x300.jpg 169w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/47-768x1365.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/47.jpg 844w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/49-576x1024.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" data-id=\"1983\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/49-576x1024.jpg\" alt=\"\" class=\"wp-image-1983\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/49-576x1024.jpg 576w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/49-300x533.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/49-84x150.jpg 84w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/49-600x1066.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/49-169x300.jpg 169w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/49-768x1365.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/49.jpg 844w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/54-576x1024.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" data-id=\"1984\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/54-576x1024.jpg\" alt=\"\" class=\"wp-image-1984\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/54-576x1024.jpg 576w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/54-300x533.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/54-84x150.jpg 84w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/54-600x1066.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/54-169x300.jpg 169w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/54-768x1365.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/54.jpg 844w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/59-1024x575.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" data-id=\"1987\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/59-1024x575.jpg\" alt=\"\" class=\"wp-image-1987\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/59-1024x575.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/59-300x169.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/59-267x150.jpg 267w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/59-600x337.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/59-150x84.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/59-768x432.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/59.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/60-1024x575.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" data-id=\"1993\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/60-1024x575.jpg\" alt=\"\" class=\"wp-image-1993\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/60-1024x575.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/60-300x169.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/60-267x150.jpg 267w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/60-600x337.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/60-150x84.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/60-768x432.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/60.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/62-1024x577.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" data-id=\"1981\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/62-1024x577.jpg\" alt=\"\" class=\"wp-image-1981\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/62-1024x577.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/62-300x169.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/62-266x150.jpg 266w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/62-600x338.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/62-150x85.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/62-768x433.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/62.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/66-576x1024.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" data-id=\"1991\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/66-576x1024.jpg\" alt=\"\" class=\"wp-image-1991\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/66-576x1024.jpg 576w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/66-300x534.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/66-84x150.jpg 84w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/66-600x1067.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/66-169x300.jpg 169w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/66-768x1366.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/66.jpg 824w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/67-576x1024.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" data-id=\"1995\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/67-576x1024.jpg\" alt=\"\" class=\"wp-image-1995\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/67-576x1024.jpg 576w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/67-300x533.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/67-84x150.jpg 84w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/67-600x1066.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/67-169x300.jpg 169w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/67-768x1365.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/67.jpg 844w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/68-1024x576.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"2001\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/68-1024x576.jpg\" alt=\"\" class=\"wp-image-2001\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/68-1024x576.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/68-300x169.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/68-267x150.jpg 267w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/68-600x338.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/68-150x84.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/68-768x432.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/68.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/71-576x1024.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" data-id=\"1997\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/71-576x1024.jpg\" alt=\"\" class=\"wp-image-1997\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/71-576x1024.jpg 576w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/71-300x533.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/71-84x150.jpg 84w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/71-600x1066.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/71-169x300.jpg 169w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/71-768x1365.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/71.jpg 844w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1620718718290-576x1024.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" data-id=\"1998\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1620718718290-576x1024.jpg\" alt=\"\" class=\"wp-image-1998\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1620718718290-576x1024.jpg 576w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1620718718290-300x533.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1620718718290-84x150.jpg 84w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1620718718290-600x1066.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1620718718290-169x300.jpg 169w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1620718718290-768x1365.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1620718718290.jpg 844w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/figure>\n<\/figure>\n<\/div>\n<\/div>\n\n<p><\/p>\n","protected":false},"featured_media":139288,"template":"","projects":[12829],"class_list":["post-15826","project","type-project","status-publish","has-post-thumbnail","hentry","projects-komercine-sporto-sale"],"acf":{"header":1378,"address":"","country":"Lietuva","year":2021,"description":"\"Evolve\" did\u017eiuojasi gal\u0117dama \u012frengti geriausius sporto centrus Lietuvoje ir u\u017e jos rib\u0173. Ne i\u0161imtis ir m\u016bs\u0173 ilgametis projektas \"Gym+\", esantis Klaip\u0117dos mieste. Tur\u0117dami beveik 4 tonas laisv\u0173j\u0173 svori\u0173, \u012fskaitant pritaikytus uretano laisvuosius svorius su lazeriu i\u0161pjautu ir uretanu u\u017epildytu sporto sal\u0117s logotipu bei pagal u\u017esakym\u0105 parinkta spalva, u\u017etikrinome, kad \"Gym+\" nariai gal\u0117t\u0173 naudotis auk\u0161\u010diausios klas\u0117s \u012franga. Kadangi hanteli\u0173 svoris gali siekti iki 60 kg, nariai gali per\u017eengti savo galimybi\u0173 ribas ir siekti savo fitneso tiksl\u0173.   <!--more-->\n\n\n\nSuprantame, kaip svarbu sukurti patogi\u0105 treniruo\u010di\u0173 aplink\u0105, tod\u0117l \"Gym+\" \u012freng\u0117me pus\u0119 stela\u017e\u0173 su integruotomis garso ir vibracijos slopinimo platformomis. \u0160ios platformos suma\u017eina triuk\u0161m\u0105 ir apsaugo nuo nepageidaujam\u0173 judesi\u0173 keliant sunk\u0173 svor\u012f, tod\u0117l treniruot\u0117s yra saugios ir malonios. \n\nM\u016bs\u0173 ergonomi\u0161ki ir patvar\u016bs treniruokliai su plok\u0161tel\u0117mis taip pat pateikiami \"Gym+\". \u0160ie treniruokliai sukurti taip, kad b\u016bt\u0173 maksimaliai patog\u016bs ir efektyv\u016bs, o j\u0173 veikla b\u016bt\u0173 nukreipta \u012f konkre\u010dias raumen\u0173 grupes. Be to, \u012freng\u0117me beveik 30 treniruo\u010di\u0173 suol\u0173, tarp j\u0173 - suol\u0173 presams, kad nariai gal\u0117t\u0173 atlikti \u012fvairius pratimus ir rinktis i\u0161 \u012fvairi\u0173 variant\u0173.  \n\nSuprantame, kad kiekvienas treniruokli\u0173 centras turi unikali\u0173 poreiki\u0173, tod\u0117l suk\u016br\u0117me specialiai \"Gym+\" pritaikyt\u0105 platform\u0173 sistem\u0105. Stulpeliai yra pasirinktos spalvos, o sistema suprojektuota atsi\u017evelgiant \u012f erdv\u0119 ir sporto sal\u0117s poreikius. \n\nKad skatintume funkcines treniruotes ir kry\u017emin\u012f treniravim\u0105si, \"Gym+\" treniruokli\u0173 sal\u0117je \u012freng\u0117me uretano kettlebell rinkinius, slam kamuolius, sieninius kamuolius, j\u0117gos mai\u0161us ir mink\u0161tus plyo bokso rinkinius. \u0160ios funkcin\u0117s treniruot\u0117s u\u017etikrina viso k\u016bno treniruot\u0119 ir gali b\u016bti pritaikytos individualiam fizinio pasirengimo lygiui. \n\nGaliausiai pateik\u0117me PVC ir NBR treniruo\u010di\u0173 kilim\u0117lius su pavaizduotu j\u0173 prek\u0117s \u017eenklo logotipu. \u0160ie auk\u0161tos kokyb\u0117s kilim\u0117liai ne tik u\u017etikrina patog\u0173 treniruo\u010di\u0173 pavir\u0161i\u0173, bet ir su pasidid\u017eiavimu reprezentuoja \"Gym+\" prek\u0117s \u017eenkl\u0105.\n\"Evolve\" siekia pateikti geriausi\u0105 treniruokli\u0173 \u012frang\u0105 ir dizain\u0105, o \"Gym+\" yra puikus m\u016bs\u0173 \u012fsipareigojimo tobul\u0117ti pavyzdys. Mums didel\u0117 garb\u0117 prisid\u0117ti prie \"Gym+\" s\u0117km\u0117s ir tikim\u0117s, kad ateityje gal\u0117sime \u012frengti dar daugiau sporto centr\u0173.  "},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gym+ Klaip\u0117da Vingis - Evolve<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-2\/\" \/>\n<meta property=\"og:locale\" content=\"lt_LT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gym+ Klaip\u0117da Vingis - Evolve\" \/>\n<meta property=\"og:description\" content=\"Projekt\u0173 galerija\" \/>\n<meta property=\"og:url\" content=\"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Evolve\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EvolveFitnessEurope\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-23T05:42:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/11\/Gym-Plius-Klaipeda-52-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1213\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/sporto-sale-2\\\/\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/sporto-sale-2\\\/\",\"name\":\"Gym+ Klaip\u0117da Vingis - Evolve\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/sporto-sale-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/sporto-sale-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Gym-Plius-Klaipeda-52-scaled.jpg\",\"datePublished\":\"2023-11-18T13:14:52+00:00\",\"dateModified\":\"2026-04-23T05:42:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/sporto-sale-2\\\/#breadcrumb\"},\"inLanguage\":\"lt-LT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/sporto-sale-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"lt-LT\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/sporto-sale-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Gym-Plius-Klaipeda-52-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Gym-Plius-Klaipeda-52-scaled.jpg\",\"width\":2560,\"height\":1213},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/sporto-sale-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gym+ Klaip\u0117da Vingis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#website\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/\",\"name\":\"Evolve\",\"description\":\"Your Evolved Gear Arrived\",\"publisher\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"lt-LT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#organization\",\"name\":\"Evolve\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"lt-LT\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Evolve-logo.svg\",\"contentUrl\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Evolve-logo.svg\",\"width\":176,\"height\":20,\"caption\":\"Evolve\"},\"image\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EvolveFitnessEurope\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gym+ Klaip\u0117da Vingis - Evolve","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-2\/","og_locale":"lt_LT","og_type":"article","og_title":"Gym+ Klaip\u0117da Vingis - Evolve","og_description":"Projekt\u0173 galerija","og_url":"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-2\/","og_site_name":"Evolve","article_publisher":"https:\/\/www.facebook.com\/EvolveFitnessEurope","article_modified_time":"2026-04-23T05:42:11+00:00","og_image":[{"width":2560,"height":1213,"url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/11\/Gym-Plius-Klaipeda-52-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-2\/","url":"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-2\/","name":"Gym+ Klaip\u0117da Vingis - Evolve","isPartOf":{"@id":"https:\/\/evolve-fitness.eu\/lt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-2\/#primaryimage"},"image":{"@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-2\/#primaryimage"},"thumbnailUrl":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/11\/Gym-Plius-Klaipeda-52-scaled.jpg","datePublished":"2023-11-18T13:14:52+00:00","dateModified":"2026-04-23T05:42:11+00:00","breadcrumb":{"@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-2\/#breadcrumb"},"inLanguage":"lt-LT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-2\/"]}]},{"@type":"ImageObject","inLanguage":"lt-LT","@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-2\/#primaryimage","url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/11\/Gym-Plius-Klaipeda-52-scaled.jpg","contentUrl":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/11\/Gym-Plius-Klaipeda-52-scaled.jpg","width":2560,"height":1213},{"@type":"BreadcrumbList","@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/evolve-fitness.eu\/lt\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/evolve-fitness.eu\/lt\/projektai\/"},{"@type":"ListItem","position":3,"name":"Gym+ Klaip\u0117da Vingis"}]},{"@type":"WebSite","@id":"https:\/\/evolve-fitness.eu\/lt\/#website","url":"https:\/\/evolve-fitness.eu\/lt\/","name":"Evolve","description":"Your Evolved Gear Arrived","publisher":{"@id":"https:\/\/evolve-fitness.eu\/lt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/evolve-fitness.eu\/lt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"lt-LT"},{"@type":"Organization","@id":"https:\/\/evolve-fitness.eu\/lt\/#organization","name":"Evolve","url":"https:\/\/evolve-fitness.eu\/lt\/","logo":{"@type":"ImageObject","inLanguage":"lt-LT","@id":"https:\/\/evolve-fitness.eu\/lt\/#\/schema\/logo\/image\/","url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/05\/Evolve-logo.svg","contentUrl":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/05\/Evolve-logo.svg","width":176,"height":20,"caption":"Evolve"},"image":{"@id":"https:\/\/evolve-fitness.eu\/lt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EvolveFitnessEurope"]}]}},"featured_image":{"id":139288,"url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/11\/Gym-Plius-Klaipeda-52-1024x485.jpg","full_url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/11\/Gym-Plius-Klaipeda-52-scaled.jpg","alt":"","width":2560,"height":1213},"_links":{"self":[{"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/project\/15826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/media\/139288"}],"wp:attachment":[{"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/media?parent=15826"}],"wp:term":[{"taxonomy":"projects","embeddable":true,"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/projects?post=15826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}