{"id":16098,"date":"2023-08-22T12:14:44","date_gmt":"2023-08-22T12:14:44","guid":{"rendered":"https:\/\/evolve-fitness.eu\/project\/sporto-sale-4\/"},"modified":"2026-04-23T10:26:46","modified_gmt":"2026-04-23T07:26:46","slug":"sporto-sale-4","status":"publish","type":"project","link":"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-4\/","title":{"rendered":"&#8222;Gym+ Vilnius Outlet Mall"},"content":{"rendered":"\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-top:var(--wp--preset--spacing--section-top);padding-bottom:var(--wp--preset--spacing--section-top);flex-basis:100%\">\n<h3 class=\"wp-block-heading alignwide\" style=\"margin-top:0;margin-bottom:var(--wp--preset--spacing--section-title-bottom)\">Projekt\u0173 galerija<\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-4 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1-10-1024x767.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"767\" data-id=\"2300\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1-10-1024x767.jpg\" alt=\"\" class=\"wp-image-2300\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1-10-1024x767.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1-10-300x225.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1-10-200x150.jpg 200w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1-10-600x449.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1-10-150x112.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1-10-768x575.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/1-10.jpg 1154w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2-7-1024x767.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"767\" data-id=\"2302\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2-7-1024x767.jpg\" alt=\"\" class=\"wp-image-2302\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2-7-1024x767.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2-7-300x225.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2-7-200x150.jpg 200w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2-7-600x449.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2-7-150x112.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2-7-768x575.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/2-7.jpg 1154w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3-7-1024x767.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"767\" data-id=\"2304\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3-7-1024x767.jpg\" alt=\"\" class=\"wp-image-2304\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3-7-1024x767.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3-7-300x225.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3-7-200x150.jpg 200w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3-7-600x449.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3-7-150x112.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3-7-768x575.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/3-7.jpg 1154w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/4-8-1024x767.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"767\" data-id=\"2306\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/4-8-1024x767.jpg\" alt=\"\" class=\"wp-image-2306\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/4-8-1024x767.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/4-8-300x225.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/4-8-200x150.jpg 200w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/4-8-600x449.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/4-8-150x112.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/4-8-768x575.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/4-8.jpg 1154w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/5-7-1024x767.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"767\" data-id=\"2310\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/5-7-1024x767.jpg\" alt=\"\" class=\"wp-image-2310\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/5-7-1024x767.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/5-7-300x225.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/5-7-200x150.jpg 200w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/5-7-600x449.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/5-7-150x112.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/5-7-768x575.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/5-7.jpg 1154w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/6-5-1024x767.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"767\" data-id=\"2308\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/6-5-1024x767.jpg\" alt=\"\" class=\"wp-image-2308\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/6-5-1024x767.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/6-5-300x225.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/6-5-200x150.jpg 200w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/6-5-600x449.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/6-5-150x112.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/6-5-768x575.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/6-5.jpg 1154w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/7-3-1024x767.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"767\" data-id=\"2314\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/7-3-1024x767.jpg\" alt=\"\" class=\"wp-image-2314\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/7-3-1024x767.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/7-3-300x225.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/7-3-200x150.jpg 200w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/7-3-600x449.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/7-3-150x112.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/7-3-768x575.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/7-3.jpg 1154w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/8-2-1024x767.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"767\" data-id=\"2312\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/8-2-1024x767.jpg\" alt=\"\" class=\"wp-image-2312\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/8-2-1024x767.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/8-2-300x225.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/8-2-200x150.jpg 200w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/8-2-600x449.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/8-2-150x112.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/8-2-768x575.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/8-2.jpg 1154w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n<\/div>\n<\/div>\n","protected":false},"featured_media":141371,"template":"","projects":[12829],"class_list":["post-16098","project","type-project","status-publish","has-post-thumbnail","hentry","projects-komercine-sporto-sale"],"acf":{"header":141371,"address":"","country":"Lietuva","year":2021,"description":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Gym+ Vilnius Outlet Mall - Evolve<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-4\/\" \/>\n<meta property=\"og:locale\" content=\"lt_LT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Gym+ Vilnius Outlet Mall - Evolve\" \/>\n<meta property=\"og:description\" content=\"Projekt\u0173 galerija\" \/>\n<meta property=\"og:url\" content=\"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Evolve\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EvolveFitnessEurope\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-23T07:26:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/Gym-Plius-Outlet-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/sporto-sale-4\\\/\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/sporto-sale-4\\\/\",\"name\":\"\\\"Gym+ Vilnius Outlet Mall - Evolve\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/sporto-sale-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/sporto-sale-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Gym-Plius-Outlet-scaled.jpg\",\"datePublished\":\"2023-08-22T12:14:44+00:00\",\"dateModified\":\"2026-04-23T07:26:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/sporto-sale-4\\\/#breadcrumb\"},\"inLanguage\":\"lt-LT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/sporto-sale-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"lt-LT\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/sporto-sale-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Gym-Plius-Outlet-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Gym-Plius-Outlet-scaled.jpg\",\"width\":2560,\"height\":1706},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/sporto-sale-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"&#8220;Gym+ Vilnius Outlet Mall\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#website\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/\",\"name\":\"Evolve\",\"description\":\"Your Evolved Gear Arrived\",\"publisher\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"lt-LT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#organization\",\"name\":\"Evolve\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"lt-LT\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Evolve-logo.svg\",\"contentUrl\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Evolve-logo.svg\",\"width\":176,\"height\":20,\"caption\":\"Evolve\"},\"image\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EvolveFitnessEurope\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Gym+ Vilnius Outlet Mall - Evolve","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-4\/","og_locale":"lt_LT","og_type":"article","og_title":"\"Gym+ Vilnius Outlet Mall - Evolve","og_description":"Projekt\u0173 galerija","og_url":"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-4\/","og_site_name":"Evolve","article_publisher":"https:\/\/www.facebook.com\/EvolveFitnessEurope","article_modified_time":"2026-04-23T07:26:46+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/Gym-Plius-Outlet-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-4\/","url":"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-4\/","name":"\"Gym+ Vilnius Outlet Mall - Evolve","isPartOf":{"@id":"https:\/\/evolve-fitness.eu\/lt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-4\/#primaryimage"},"image":{"@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-4\/#primaryimage"},"thumbnailUrl":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/Gym-Plius-Outlet-scaled.jpg","datePublished":"2023-08-22T12:14:44+00:00","dateModified":"2026-04-23T07:26:46+00:00","breadcrumb":{"@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-4\/#breadcrumb"},"inLanguage":"lt-LT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-4\/"]}]},{"@type":"ImageObject","inLanguage":"lt-LT","@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-4\/#primaryimage","url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/Gym-Plius-Outlet-scaled.jpg","contentUrl":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/Gym-Plius-Outlet-scaled.jpg","width":2560,"height":1706},{"@type":"BreadcrumbList","@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/sporto-sale-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/evolve-fitness.eu\/lt\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/evolve-fitness.eu\/lt\/projektai\/"},{"@type":"ListItem","position":3,"name":"&#8220;Gym+ Vilnius Outlet Mall"}]},{"@type":"WebSite","@id":"https:\/\/evolve-fitness.eu\/lt\/#website","url":"https:\/\/evolve-fitness.eu\/lt\/","name":"Evolve","description":"Your Evolved Gear Arrived","publisher":{"@id":"https:\/\/evolve-fitness.eu\/lt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/evolve-fitness.eu\/lt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"lt-LT"},{"@type":"Organization","@id":"https:\/\/evolve-fitness.eu\/lt\/#organization","name":"Evolve","url":"https:\/\/evolve-fitness.eu\/lt\/","logo":{"@type":"ImageObject","inLanguage":"lt-LT","@id":"https:\/\/evolve-fitness.eu\/lt\/#\/schema\/logo\/image\/","url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/05\/Evolve-logo.svg","contentUrl":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/05\/Evolve-logo.svg","width":176,"height":20,"caption":"Evolve"},"image":{"@id":"https:\/\/evolve-fitness.eu\/lt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EvolveFitnessEurope"]}]}},"featured_image":{"id":141371,"url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/Gym-Plius-Outlet-1024x682.jpg","full_url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/Gym-Plius-Outlet-scaled.jpg","alt":"","width":2560,"height":1706},"_links":{"self":[{"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/project\/16098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/media\/141371"}],"wp:attachment":[{"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/media?parent=16098"}],"wp:term":[{"taxonomy":"projects","embeddable":true,"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/projects?post=16098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}