{"id":16103,"date":"2023-08-25T13:14:20","date_gmt":"2023-08-25T13:14:20","guid":{"rendered":"https:\/\/evolve-fitness.eu\/project\/lfff-2023\/"},"modified":"2026-04-23T10:23:27","modified_gmt":"2026-04-23T07:23:27","slug":"lfff-2023","status":"publish","type":"project","link":"https:\/\/evolve-fitness.eu\/lt\/projektai\/lfff-2023\/","title":{"rendered":"LFF 2023"},"content":{"rendered":"\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-top:var(--wp--preset--spacing--section-top);padding-bottom:var(--wp--preset--spacing--section-top);flex-basis:100%\">\n<h3 class=\"wp-block-heading alignwide\" style=\"margin-top:0;margin-bottom:var(--wp--preset--spacing--section-title-bottom)\">Projekt\u0173 galerija<\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-4 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363362922_693050136198391_1467934126229409230_n-1024x688.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"688\" data-id=\"3155\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363362922_693050136198391_1467934126229409230_n-1024x688.jpg\" alt=\"\" class=\"wp-image-3155\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363362922_693050136198391_1467934126229409230_n-1024x688.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363362922_693050136198391_1467934126229409230_n-300x201.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363362922_693050136198391_1467934126229409230_n-223x150.jpg 223w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363362922_693050136198391_1467934126229409230_n-600x403.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363362922_693050136198391_1467934126229409230_n-150x101.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363362922_693050136198391_1467934126229409230_n-768x516.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363362922_693050136198391_1467934126229409230_n.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363509536_653722759998551_8873406988588261666_n-822x1024.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"822\" height=\"1024\" data-id=\"3124\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363509536_653722759998551_8873406988588261666_n-822x1024.jpg\" alt=\"\" class=\"wp-image-3124\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363509536_653722759998551_8873406988588261666_n-822x1024.jpg 822w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363509536_653722759998551_8873406988588261666_n-300x374.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363509536_653722759998551_8873406988588261666_n-120x150.jpg 120w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363509536_653722759998551_8873406988588261666_n-600x748.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363509536_653722759998551_8873406988588261666_n-241x300.jpg 241w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363509536_653722759998551_8873406988588261666_n-768x957.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363509536_653722759998551_8873406988588261666_n-1233x1536.jpg 1233w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363509536_653722759998551_8873406988588261666_n.jpg 1326w\" sizes=\"auto, (max-width: 822px) 100vw, 822px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363531231_1736957386762346_6436121303356857506_n-819x1024.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"3118\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363531231_1736957386762346_6436121303356857506_n-819x1024.jpg\" alt=\"\" class=\"wp-image-3118\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363531231_1736957386762346_6436121303356857506_n-819x1024.jpg 819w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363531231_1736957386762346_6436121303356857506_n-300x375.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363531231_1736957386762346_6436121303356857506_n-120x150.jpg 120w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363531231_1736957386762346_6436121303356857506_n-600x750.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363531231_1736957386762346_6436121303356857506_n-240x300.jpg 240w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363531231_1736957386762346_6436121303356857506_n-768x960.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363531231_1736957386762346_6436121303356857506_n.jpg 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363837401_599772055571902_8354441624128836548_n-819x1024.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"3116\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363837401_599772055571902_8354441624128836548_n-819x1024.jpg\" alt=\"\" class=\"wp-image-3116\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363837401_599772055571902_8354441624128836548_n-819x1024.jpg 819w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363837401_599772055571902_8354441624128836548_n-300x375.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363837401_599772055571902_8354441624128836548_n-120x150.jpg 120w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363837401_599772055571902_8354441624128836548_n-600x750.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363837401_599772055571902_8354441624128836548_n-240x300.jpg 240w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363837401_599772055571902_8354441624128836548_n-768x960.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363837401_599772055571902_8354441624128836548_n.jpg 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363895998_1018947506214168_3034239287644138931_n-821x1024.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"821\" height=\"1024\" data-id=\"3120\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363895998_1018947506214168_3034239287644138931_n-821x1024.jpg\" alt=\"\" class=\"wp-image-3120\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363895998_1018947506214168_3034239287644138931_n-821x1024.jpg 821w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363895998_1018947506214168_3034239287644138931_n-300x374.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363895998_1018947506214168_3034239287644138931_n-120x150.jpg 120w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363895998_1018947506214168_3034239287644138931_n-600x748.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363895998_1018947506214168_3034239287644138931_n-241x300.jpg 241w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363895998_1018947506214168_3034239287644138931_n-768x957.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363895998_1018947506214168_3034239287644138931_n-1232x1536.jpg 1232w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363895998_1018947506214168_3034239287644138931_n.jpg 1314w\" sizes=\"auto, (max-width: 821px) 100vw, 821px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363934530_692578329578905_3101251022907446241_n-1024x686.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"686\" data-id=\"3119\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363934530_692578329578905_3101251022907446241_n-1024x686.jpg\" alt=\"\" class=\"wp-image-3119\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363934530_692578329578905_3101251022907446241_n-1024x686.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363934530_692578329578905_3101251022907446241_n-300x201.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363934530_692578329578905_3101251022907446241_n-224x150.jpg 224w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363934530_692578329578905_3101251022907446241_n-600x402.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363934530_692578329578905_3101251022907446241_n-150x100.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363934530_692578329578905_3101251022907446241_n-768x514.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363934530_692578329578905_3101251022907446241_n.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363970265_693050132865058_9163887615803732981_n-1024x686.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"686\" data-id=\"3131\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363970265_693050132865058_9163887615803732981_n-1024x686.jpg\" alt=\"\" class=\"wp-image-3131\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363970265_693050132865058_9163887615803732981_n-1024x686.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363970265_693050132865058_9163887615803732981_n-300x201.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363970265_693050132865058_9163887615803732981_n-224x150.jpg 224w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363970265_693050132865058_9163887615803732981_n-600x402.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363970265_693050132865058_9163887615803732981_n-150x101.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363970265_693050132865058_9163887615803732981_n-768x515.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363970265_693050132865058_9163887615803732981_n.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363972871_692578322912239_8628534698530616228_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"685\" data-id=\"3128\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363972871_692578322912239_8628534698530616228_n-1024x685.jpg\" alt=\"\" class=\"wp-image-3128\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363972871_692578322912239_8628534698530616228_n-1024x685.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363972871_692578322912239_8628534698530616228_n-300x201.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363972871_692578322912239_8628534698530616228_n-224x150.jpg 224w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363972871_692578322912239_8628534698530616228_n-600x401.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363972871_692578322912239_8628534698530616228_n-150x100.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363972871_692578322912239_8628534698530616228_n-768x514.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363972871_692578322912239_8628534698530616228_n.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363976188_693050139531724_7040477486510354024_n-1024x688.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"688\" data-id=\"3135\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363976188_693050139531724_7040477486510354024_n-1024x688.jpg\" alt=\"\" class=\"wp-image-3135\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363976188_693050139531724_7040477486510354024_n-1024x688.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363976188_693050139531724_7040477486510354024_n-300x201.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363976188_693050139531724_7040477486510354024_n-223x150.jpg 223w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363976188_693050139531724_7040477486510354024_n-600x403.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363976188_693050139531724_7040477486510354024_n-150x101.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363976188_693050139531724_7040477486510354024_n-768x516.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363976188_693050139531724_7040477486510354024_n.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363984099_693199449516793_478620583753436222_n-819x1024.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"3132\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363984099_693199449516793_478620583753436222_n-819x1024.jpg\" alt=\"\" class=\"wp-image-3132\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363984099_693199449516793_478620583753436222_n-819x1024.jpg 819w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363984099_693199449516793_478620583753436222_n-300x375.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363984099_693199449516793_478620583753436222_n-120x150.jpg 120w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363984099_693199449516793_478620583753436222_n-600x750.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363984099_693199449516793_478620583753436222_n-240x300.jpg 240w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363984099_693199449516793_478620583753436222_n-768x960.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363984099_693199449516793_478620583753436222_n-1229x1536.jpg 1229w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363984099_693199449516793_478620583753436222_n.jpg 1440w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363990625_692578332912238_1183030006657332330_n-1-1024x685.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"685\" data-id=\"3129\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363990625_692578332912238_1183030006657332330_n-1-1024x685.jpg\" alt=\"\" class=\"wp-image-3129\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363990625_692578332912238_1183030006657332330_n-1-1024x685.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363990625_692578332912238_1183030006657332330_n-1-300x201.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363990625_692578332912238_1183030006657332330_n-1-224x150.jpg 224w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363990625_692578332912238_1183030006657332330_n-1-600x401.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363990625_692578332912238_1183030006657332330_n-1-150x100.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363990625_692578332912238_1183030006657332330_n-1-768x514.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363990625_692578332912238_1183030006657332330_n-1.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363991842_693199459516792_1556312101360595606_n-819x1024.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"3139\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363991842_693199459516792_1556312101360595606_n-819x1024.jpg\" alt=\"\" class=\"wp-image-3139\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363991842_693199459516792_1556312101360595606_n-819x1024.jpg 819w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363991842_693199459516792_1556312101360595606_n-300x375.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363991842_693199459516792_1556312101360595606_n-120x150.jpg 120w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363991842_693199459516792_1556312101360595606_n-600x750.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363991842_693199459516792_1556312101360595606_n-240x300.jpg 240w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363991842_693199459516792_1556312101360595606_n-768x960.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363991842_693199459516792_1556312101360595606_n-1229x1536.jpg 1229w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363991842_693199459516792_1556312101360595606_n.jpg 1431w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363995910_693199462850125_3802066360141108880_n-819x1024.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"3141\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363995910_693199462850125_3802066360141108880_n-819x1024.jpg\" alt=\"\" class=\"wp-image-3141\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363995910_693199462850125_3802066360141108880_n-819x1024.jpg 819w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363995910_693199462850125_3802066360141108880_n-300x375.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363995910_693199462850125_3802066360141108880_n-120x150.jpg 120w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363995910_693199462850125_3802066360141108880_n-600x750.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363995910_693199462850125_3802066360141108880_n-240x300.jpg 240w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363995910_693199462850125_3802066360141108880_n-768x960.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363995910_693199462850125_3802066360141108880_n-1229x1536.jpg 1229w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363995910_693199462850125_3802066360141108880_n.jpg 1440w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364001508_693199456183459_6311491415473897592_n-819x1024.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"3145\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364001508_693199456183459_6311491415473897592_n-819x1024.jpg\" alt=\"\" class=\"wp-image-3145\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364001508_693199456183459_6311491415473897592_n-819x1024.jpg 819w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364001508_693199456183459_6311491415473897592_n-300x375.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364001508_693199456183459_6311491415473897592_n-120x150.jpg 120w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364001508_693199456183459_6311491415473897592_n-600x750.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364001508_693199456183459_6311491415473897592_n-240x300.jpg 240w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364001508_693199456183459_6311491415473897592_n-768x960.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364001508_693199456183459_6311491415473897592_n-1229x1536.jpg 1229w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364001508_693199456183459_6311491415473897592_n.jpg 1440w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364006675_693199439516794_6207024896920026644_n-819x1024.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"3151\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364006675_693199439516794_6207024896920026644_n-819x1024.jpg\" alt=\"\" class=\"wp-image-3151\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364006675_693199439516794_6207024896920026644_n-819x1024.jpg 819w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364006675_693199439516794_6207024896920026644_n-300x375.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364006675_693199439516794_6207024896920026644_n-120x150.jpg 120w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364006675_693199439516794_6207024896920026644_n-600x750.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364006675_693199439516794_6207024896920026644_n-240x300.jpg 240w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364006675_693199439516794_6207024896920026644_n-768x960.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364006675_693199439516794_6207024896920026644_n-1229x1536.jpg 1229w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364006675_693199439516794_6207024896920026644_n.jpg 1440w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364014924_693345169502221_1994837298456550463_n-819x1024.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"3147\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364014924_693345169502221_1994837298456550463_n-819x1024.jpg\" alt=\"\" class=\"wp-image-3147\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364014924_693345169502221_1994837298456550463_n-819x1024.jpg 819w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364014924_693345169502221_1994837298456550463_n-300x375.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364014924_693345169502221_1994837298456550463_n-120x150.jpg 120w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364014924_693345169502221_1994837298456550463_n-600x750.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364014924_693345169502221_1994837298456550463_n-240x300.jpg 240w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364014924_693345169502221_1994837298456550463_n-768x960.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364014924_693345169502221_1994837298456550463_n-1229x1536.jpg 1229w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364014924_693345169502221_1994837298456550463_n.jpg 1440w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364016298_693050109531727_3343447781273727155_n-1024x688.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"688\" data-id=\"3143\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364016298_693050109531727_3343447781273727155_n-1024x688.jpg\" alt=\"\" class=\"wp-image-3143\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364016298_693050109531727_3343447781273727155_n-1024x688.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364016298_693050109531727_3343447781273727155_n-300x201.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364016298_693050109531727_3343447781273727155_n-223x150.jpg 223w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364016298_693050109531727_3343447781273727155_n-600x403.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364016298_693050109531727_3343447781273727155_n-150x101.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364016298_693050109531727_3343447781273727155_n-768x516.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364016298_693050109531727_3343447781273727155_n.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364038951_693050122865059_4793776293789321140_n-1024x688.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"688\" data-id=\"3149\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364038951_693050122865059_4793776293789321140_n-1024x688.jpg\" alt=\"\" class=\"wp-image-3149\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364038951_693050122865059_4793776293789321140_n-1024x688.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364038951_693050122865059_4793776293789321140_n-300x201.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364038951_693050122865059_4793776293789321140_n-223x150.jpg 223w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364038951_693050122865059_4793776293789321140_n-600x403.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364038951_693050122865059_4793776293789321140_n-150x101.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364038951_693050122865059_4793776293789321140_n-768x516.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364038951_693050122865059_4793776293789321140_n.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364183763_245266151717985_3305630043671573658_n-819x1024.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"3153\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364183763_245266151717985_3305630043671573658_n-819x1024.jpg\" alt=\"\" class=\"wp-image-3153\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364183763_245266151717985_3305630043671573658_n-819x1024.jpg 819w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364183763_245266151717985_3305630043671573658_n-300x375.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364183763_245266151717985_3305630043671573658_n-120x150.jpg 120w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364183763_245266151717985_3305630043671573658_n-600x750.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364183763_245266151717985_3305630043671573658_n-240x300.jpg 240w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364183763_245266151717985_3305630043671573658_n-768x960.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/364183763_245266151717985_3305630043671573658_n.jpg 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363357270_692684609568277_4165412920826985492_n-1-819x1024.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"3162\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363357270_692684609568277_4165412920826985492_n-1-819x1024.jpg\" alt=\"\" class=\"wp-image-3162\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363357270_692684609568277_4165412920826985492_n-1-819x1024.jpg 819w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363357270_692684609568277_4165412920826985492_n-1-300x375.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363357270_692684609568277_4165412920826985492_n-1-120x150.jpg 120w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363357270_692684609568277_4165412920826985492_n-1-600x750.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363357270_692684609568277_4165412920826985492_n-1-240x300.jpg 240w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363357270_692684609568277_4165412920826985492_n-1-768x960.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363357270_692684609568277_4165412920826985492_n-1-1229x1536.jpg 1229w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363357270_692684609568277_4165412920826985492_n-1.jpg 1440w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363447807_692578326245572_1020218223164738388_n-1-1024x685.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"685\" data-id=\"3165\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363447807_692578326245572_1020218223164738388_n-1-1024x685.jpg\" alt=\"\" class=\"wp-image-3165\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363447807_692578326245572_1020218223164738388_n-1-1024x685.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363447807_692578326245572_1020218223164738388_n-1-300x201.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363447807_692578326245572_1020218223164738388_n-1-224x150.jpg 224w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363447807_692578326245572_1020218223164738388_n-1-600x401.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363447807_692578326245572_1020218223164738388_n-1-150x100.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363447807_692578326245572_1020218223164738388_n-1-768x514.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363447807_692578326245572_1020218223164738388_n-1.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363362922_693050136198391_1467934126229409230_n-1-1024x688.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"688\" data-id=\"3161\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363362922_693050136198391_1467934126229409230_n-1-1024x688.jpg\" alt=\"\" class=\"wp-image-3161\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363362922_693050136198391_1467934126229409230_n-1-1024x688.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363362922_693050136198391_1467934126229409230_n-1-300x201.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363362922_693050136198391_1467934126229409230_n-1-223x150.jpg 223w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363362922_693050136198391_1467934126229409230_n-1-600x403.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363362922_693050136198391_1467934126229409230_n-1-150x101.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363362922_693050136198391_1467934126229409230_n-1-768x516.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/363362922_693050136198391_1467934126229409230_n-1.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n<\/div>\n<\/div>\n","protected":false},"featured_media":139442,"template":"","projects":[12905],"class_list":["post-16103","project","type-project","status-publish","has-post-thumbnail","hentry","projects-renginiai"],"acf":{"header":3125,"address":"","country":"Lietuva","year":2023,"description":"Did\u017eiuojam\u0117s 2023 m. Lietuvos funkcinio fitneso \u010dempionato partneriais\n\n\"Evolve\" tikime, kad puosel\u0117jame konkurencijos, atsidavimo ir meistri\u0161kumo dvasi\u0105 funkcinio fitneso srityje. D\u017eiaugiam\u0117s gal\u0117dami prane\u0161ti apie bendradarbiavim\u0105 su Lietuvos funkcinio fitneso federacija, teikian\u010dia b\u016btiniausi\u0105 \u012frang\u0105 2023 m. Lietuvos funkcinio fitneso \u010dempionatui - did\u017eiausiam funkcinio fitneso renginiui Baltijos \u0161alyse! \n\n\u012e\u017eiebti meistri\u0161kum\u0105 did\u017eiojoje scenoje  \n\nPer dvi jaudinan\u010dias dienas daugiau nei 120 \u012fvairi\u0173 kategorij\u0173 dalyvi\u0173 susirinko pademonstruoti savo j\u0117g\u0105, vikrum\u0105 ir ry\u017et\u0105. Kai jie per\u017eeng\u0117 savo ribas, \u012fveik\u0117 kli\u016btis ir pasiek\u0117 nauj\u0173 auk\u0161tum\u0173, \"Evolve\" buvo \u0161alia ir palaik\u0117 kiekvien\u0105 pakilim\u0105, kiekvien\u0105 \u0161uol\u012f ir kiekvien\u0105 triumf\u0105. \n\nVeiklos efektyvumo didinimas naudojant \"Premier\" \u012frang\u0105\n\nD\u017eiaugiam\u0117s, kad \u0161iam fenomenaliam renginiui suteik\u0117me 6,5 tonos auk\u0161\u010diausios klas\u0117s laisv\u0173j\u0173 svori\u0173, kad kiekvienas sportininkas tur\u0117t\u0173 geriausius \u012frankius tobul\u0117ti. \u012erang\u0105 sudar\u0117: \n<!--more-->\n\n\n  \"Evolve\" \u0161e\u0161iakampiai hanteliai, skirti tikslumui ir galiai.\n  \"Evolve X Bumper Weight Plates\", u\u017etikrinan\u010dios ilgaam\u017ei\u0161kum\u0105 ir na\u0161um\u0105.\n  \"Evolve\" ketaus svarmenys universaliam j\u0117gos treniravimui.\n  Dinami\u0161koms treniruot\u0117ms skirti \"Evolve Carbon\" serijos sieniniai kamuoliai.\n  \"Evolve\" medin\u0117 plyo d\u0117\u017e\u0117 \"3-in-1\" su trimis integruotomis auk\u0161\u010dio parinktimis (51 cm, 61 cm, 76 cm) pritaikyta \u012fvairiems treniruo\u010di\u0173 poreikiams.\n\nStipryb\u0117s, ry\u017eto ir bendruomen\u0117s \u0161ventimas\n\n2023 m. Lietuvos funkcinio fitneso \u010dempionatas buvo ne tik var\u017eybos, bet ir \u017emogi\u0161kojo potencialo bei draugyst\u0117s \u0161vent\u0117. Be galo did\u017eiuojam\u0117s, kad gal\u0117jome prisid\u0117ti prie \u0161i\u0173 ne\u012ftik\u0117tin\u0173 sportinink\u0173, kurie per\u017eeng\u0117 savo galimybi\u0173 ribas ir pasiek\u0117 auk\u0161tum\u0173, r\u0117mimo. \n\nNuo\u0161irdi pad\u0117ka\n\nYpatingai d\u0117kojame Lietuvos funkcinio fitneso federacijai u\u017e tai, kad patik\u0117jo mums tiekti \u012frang\u0105 \u0161iam svarbiam renginiui. Man didel\u0117 garb\u0117 prisid\u0117ti prie renginio, kuris suburia sportininkus, trenerius ir fitneso entuziastus, siekian\u010dius meistri\u0161kumo. \n\nApm\u0105stydami 2023 m. Lietuvos funkcinio fitneso \u010dempionato s\u0117km\u0119, kvie\u010diame susipa\u017einti su \"Evolve\" pasauliu. Nesvarbu, ar esate sportininkas, sporto sal\u0117s savininkas, ar fitneso entuziastas, mes turime \u012franki\u0173 ir \u012frangos, kad pagerintum\u0117te savo sveikatingumo kelion\u0119. "},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LFF 2023 - Evolve<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/evolve-fitness.eu\/lt\/projektai\/lfff-2023\/\" \/>\n<meta property=\"og:locale\" content=\"lt_LT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LFF 2023 - Evolve\" \/>\n<meta property=\"og:description\" content=\"Projekt\u0173 galerija\" \/>\n<meta property=\"og:url\" content=\"https:\/\/evolve-fitness.eu\/lt\/projektai\/lfff-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Evolve\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EvolveFitnessEurope\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-23T07:23:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/6KT8029.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1107\" \/>\n\t<meta property=\"og:image:height\" content=\"1107\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/lfff-2023\\\/\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/lfff-2023\\\/\",\"name\":\"LFF 2023 - Evolve\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/lfff-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/lfff-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/6KT8029.jpg\",\"datePublished\":\"2023-08-25T13:14:20+00:00\",\"dateModified\":\"2026-04-23T07:23:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/lfff-2023\\\/#breadcrumb\"},\"inLanguage\":\"lt-LT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/lfff-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"lt-LT\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/lfff-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/6KT8029.jpg\",\"contentUrl\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/6KT8029.jpg\",\"width\":1107,\"height\":1107},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/lfff-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LFF 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#website\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/\",\"name\":\"Evolve\",\"description\":\"Your Evolved Gear Arrived\",\"publisher\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"lt-LT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#organization\",\"name\":\"Evolve\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"lt-LT\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Evolve-logo.svg\",\"contentUrl\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Evolve-logo.svg\",\"width\":176,\"height\":20,\"caption\":\"Evolve\"},\"image\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EvolveFitnessEurope\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LFF 2023 - Evolve","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/evolve-fitness.eu\/lt\/projektai\/lfff-2023\/","og_locale":"lt_LT","og_type":"article","og_title":"LFF 2023 - Evolve","og_description":"Projekt\u0173 galerija","og_url":"https:\/\/evolve-fitness.eu\/lt\/projektai\/lfff-2023\/","og_site_name":"Evolve","article_publisher":"https:\/\/www.facebook.com\/EvolveFitnessEurope","article_modified_time":"2026-04-23T07:23:27+00:00","og_image":[{"width":1107,"height":1107,"url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/6KT8029.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/lfff-2023\/","url":"https:\/\/evolve-fitness.eu\/lt\/projektai\/lfff-2023\/","name":"LFF 2023 - Evolve","isPartOf":{"@id":"https:\/\/evolve-fitness.eu\/lt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/lfff-2023\/#primaryimage"},"image":{"@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/lfff-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/6KT8029.jpg","datePublished":"2023-08-25T13:14:20+00:00","dateModified":"2026-04-23T07:23:27+00:00","breadcrumb":{"@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/lfff-2023\/#breadcrumb"},"inLanguage":"lt-LT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/evolve-fitness.eu\/lt\/projektai\/lfff-2023\/"]}]},{"@type":"ImageObject","inLanguage":"lt-LT","@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/lfff-2023\/#primaryimage","url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/6KT8029.jpg","contentUrl":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/6KT8029.jpg","width":1107,"height":1107},{"@type":"BreadcrumbList","@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/lfff-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/evolve-fitness.eu\/lt\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/evolve-fitness.eu\/lt\/projektai\/"},{"@type":"ListItem","position":3,"name":"LFF 2023"}]},{"@type":"WebSite","@id":"https:\/\/evolve-fitness.eu\/lt\/#website","url":"https:\/\/evolve-fitness.eu\/lt\/","name":"Evolve","description":"Your Evolved Gear Arrived","publisher":{"@id":"https:\/\/evolve-fitness.eu\/lt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/evolve-fitness.eu\/lt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"lt-LT"},{"@type":"Organization","@id":"https:\/\/evolve-fitness.eu\/lt\/#organization","name":"Evolve","url":"https:\/\/evolve-fitness.eu\/lt\/","logo":{"@type":"ImageObject","inLanguage":"lt-LT","@id":"https:\/\/evolve-fitness.eu\/lt\/#\/schema\/logo\/image\/","url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/05\/Evolve-logo.svg","contentUrl":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/05\/Evolve-logo.svg","width":176,"height":20,"caption":"Evolve"},"image":{"@id":"https:\/\/evolve-fitness.eu\/lt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EvolveFitnessEurope"]}]}},"featured_image":{"id":139442,"url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/6KT8029-1024x1024.jpg","full_url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/08\/6KT8029.jpg","alt":"","width":1107,"height":1107},"_links":{"self":[{"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/project\/16103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/media\/139442"}],"wp:attachment":[{"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/media?parent=16103"}],"wp:term":[{"taxonomy":"projects","embeddable":true,"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/projects?post=16103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}