{"id":232971,"date":"2026-02-24T14:09:30","date_gmt":"2026-02-24T12:09:30","guid":{"rendered":"https:\/\/evolve-fitness.eu\/project\/bigz-sporto-sale\/"},"modified":"2026-04-22T18:52:15","modified_gmt":"2026-04-22T15:52:15","slug":"bigz-sporto-sale","status":"publish","type":"project","link":"https:\/\/evolve-fitness.eu\/lt\/projektai\/bigz-sporto-sale\/","title":{"rendered":"&#8222;Bigz&#8221; sporto sal\u0117"},"content":{"rendered":"\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-top:var(--wp--preset--spacing--section-top);padding-bottom:var(--wp--preset--spacing--section-top);flex-basis:100%\">\n<h3 class=\"wp-block-heading alignwide\" style=\"margin-top:0;margin-bottom:var(--wp--preset--spacing--section-title-bottom)\">Projekt\u0173 galerija<\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-4 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-rounded\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"223302\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image1-1024x768.jpg\" alt=\"\" class=\"wp-image-223302\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image1-1024x768.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image1-300x225.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image1-150x113.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image1-768x576.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image1-1536x1152.jpg 1536w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image1-2048x1536.jpg 2048w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image1-600x450.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image1-200x150.jpg 200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-style-rounded\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" data-id=\"223298\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz-scaled.jpg\" alt=\"\" class=\"wp-image-223298\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz-scaled.jpg 2560w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz-300x225.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz-1024x768.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz-150x113.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz-768x576.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz-1536x1152.jpg 1536w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz-2048x1536.jpg 2048w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz-600x450.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz-200x150.jpg 200w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-style-rounded\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz2-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"223300\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz2-1024x768.jpg\" alt=\"\" class=\"wp-image-223300\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz2-1024x768.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz2-300x225.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz2-150x113.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz2-768x576.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz2-1536x1152.jpg 1536w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz2-2048x1536.jpg 2048w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz2-600x450.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz2-200x150.jpg 200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-style-rounded\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image2-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"223301\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image2-1024x768.jpg\" alt=\"\" class=\"wp-image-223301\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image2-1024x768.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image2-300x225.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image2-150x113.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image2-768x576.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image2-1536x1152.jpg 1536w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image2-2048x1536.jpg 2048w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image2-600x450.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image2-200x150.jpg 200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-style-rounded\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"223299\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz1-1024x768.jpg\" alt=\"\" class=\"wp-image-223299\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz1-1024x768.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz1-300x225.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz1-150x113.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz1-768x576.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz1-1536x1152.jpg 1536w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz1-2048x1536.jpg 2048w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz1-600x450.jpg 600w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz1-200x150.jpg 200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-style-rounded\"><a href=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image0-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"223303\" src=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image0-1024x1024.jpg\" alt=\"\" class=\"wp-image-223303\" srcset=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image0-1024x1024.jpg 1024w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image0-300x300.jpg 300w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image0-150x150.jpg 150w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image0-768x768.jpg 768w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image0-1536x1536.jpg 1536w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image0-2048x2048.jpg 2048w, https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/image0-600x600.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n<\/div>\n<\/div>\n","protected":false},"featured_media":232973,"template":"","projects":[12829,13042],"class_list":["post-232971","project","type-project","status-publish","has-post-thumbnail","hentry","projects-komercine-sporto-sale","projects-sporto-sale-studio-gym"],"acf":{"header":232976,"address":"","country":"Lietuva","year":2026,"description":"\u0160\u012f treniruokli\u0173 studijos projekt\u0105 Bir\u017euose, Lietuvoje, apr\u016bpinome kruop\u0161\u010diai atrinktais \"Evolve\" komerciniais treniruokliais, skirtais j\u0117gos treniruot\u0117ms, \" <a href=\"https:\/\/evolve-fitness.eu\/product-category\/cardio-equipment\/commercial-cardio-equipment\/ultra-series-cardio\/\" target=\"_blank\">Ultra Series Cardio\"<\/a> ir <a href=\"https:\/\/evolve-fitness.eu\/product\/non-motorized-treadmill-with-resistance\/\" target=\"_blank\">nemotorizuotais b\u0117gimo takeliais su pasiprie\u0161inimu<\/a> bei <a href=\"https:\/\/evolve-fitness.eu\/product-category\/free-weights\/\" target=\"_blank\">laisvojo svorio zona,<\/a> modernia treniruo\u010di\u0173 aplinka, pritaikyta \u012fvairiems vartotoj\u0173 poreikiams.\n\n\u012erenginyje yra laisvojo svorio treniruokliai, pvz: \" <a href=\"https:\/\/evolve-fitness.eu\/product\/evolve-hi-temp-x-bumper-weight-plates-5-25-kg\/\" target=\"_blank\">Evolve Hi-Temp X Bumper Weight Plates\"<\/a>, <a href=\"https:\/\/evolve-fitness.eu\/product\/evolve-tpu-urethane-dumbbell-set-10-60kg\/\" target=\"_blank\">\"Evolve TPU Urethane Dumbbell Set 10-60 kg\", \"<\/a> <a href=\"https:\/\/evolve-fitness.eu\/product\/evolve-cpu-urethane-dumbbells-set-2-x-1-10-kg\/\" target=\"_blank\">CPU Urethane Dumbbell Set 1-10 kg\",<\/a> taip pat papildomas \" <a href=\"https:\/\/evolve-fitness.eu\/product\/evolve-econ-series-adjustable-bench-ec-100\/\" target=\"_blank\">Econ Series\" reguliuojamas suoliukas, \"<\/a> <a href=\"https:\/\/evolve-fitness.eu\/product-category\/platforms\/platforms-2\/\" target=\"_blank\">Powerlifting Sound & Vibration Absorption Platform\"<\/a> ir \" <a href=\"https:\/\/evolve-fitness.eu\/product-category\/cross-functional\/power-racks\/\" target=\"_blank\">Power Rack\"<\/a>, skirtas patogiai treniruotis.  \n\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Bigz&quot; sporto sal\u0117 - Evolve<\/title>\n<meta name=\"description\" content=\"\u0160\u012f fitneso STUDIJOS projekt\u0105 Bir\u017euose, Lietuvoje, apr\u016bpinome kruop\u0161\u010diai atrinkta &quot;Evolve&quot; komercine treniruokli\u0173 \u012franga.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/evolve-fitness.eu\/lt\/projektai\/bigz-sporto-sale\/\" \/>\n<meta property=\"og:locale\" content=\"lt_LT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Bigz&quot; sporto sal\u0117 - Evolve\" \/>\n<meta property=\"og:description\" content=\"\u0160\u012f fitneso STUDIJOS projekt\u0105 Bir\u017euose, Lietuvoje, apr\u016bpinome kruop\u0161\u010diai atrinkta &quot;Evolve&quot; komercine treniruokli\u0173 \u012franga.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/evolve-fitness.eu\/lt\/projektai\/bigz-sporto-sale\/\" \/>\n<meta property=\"og:site_name\" content=\"Evolve\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EvolveFitnessEurope\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-22T15:52:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/bigz-sporto-sale\\\/\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/bigz-sporto-sale\\\/\",\"name\":\"\\\"Bigz\\\" sporto sal\u0117 - Evolve\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/bigz-sporto-sale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/bigz-sporto-sale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/bigz2-scaled.jpg\",\"datePublished\":\"2026-02-24T12:09:30+00:00\",\"dateModified\":\"2026-04-22T15:52:15+00:00\",\"description\":\"\u0160\u012f fitneso STUDIJOS projekt\u0105 Bir\u017euose, Lietuvoje, apr\u016bpinome kruop\u0161\u010diai atrinkta \\\"Evolve\\\" komercine treniruokli\u0173 \u012franga.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/bigz-sporto-sale\\\/#breadcrumb\"},\"inLanguage\":\"lt-LT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/bigz-sporto-sale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"lt-LT\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/bigz-sporto-sale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/bigz2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/bigz2-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/bigz-sporto-sale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/projektai\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"&#8220;Bigz&#8221; sporto sal\u0117\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#website\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/\",\"name\":\"Evolve\",\"description\":\"Your Evolved Gear Arrived\",\"publisher\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"lt-LT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#organization\",\"name\":\"Evolve\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"lt-LT\",\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Evolve-logo.svg\",\"contentUrl\":\"https:\\\/\\\/evolve-fitness.eu\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Evolve-logo.svg\",\"width\":176,\"height\":20,\"caption\":\"Evolve\"},\"image\":{\"@id\":\"https:\\\/\\\/evolve-fitness.eu\\\/lt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EvolveFitnessEurope\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Bigz\" sporto sal\u0117 - Evolve","description":"\u0160\u012f fitneso STUDIJOS projekt\u0105 Bir\u017euose, Lietuvoje, apr\u016bpinome kruop\u0161\u010diai atrinkta \"Evolve\" komercine treniruokli\u0173 \u012franga.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/evolve-fitness.eu\/lt\/projektai\/bigz-sporto-sale\/","og_locale":"lt_LT","og_type":"article","og_title":"\"Bigz\" sporto sal\u0117 - Evolve","og_description":"\u0160\u012f fitneso STUDIJOS projekt\u0105 Bir\u017euose, Lietuvoje, apr\u016bpinome kruop\u0161\u010diai atrinkta \"Evolve\" komercine treniruokli\u0173 \u012franga.","og_url":"https:\/\/evolve-fitness.eu\/lt\/projektai\/bigz-sporto-sale\/","og_site_name":"Evolve","article_publisher":"https:\/\/www.facebook.com\/EvolveFitnessEurope","article_modified_time":"2026-04-22T15:52:15+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz2-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/bigz-sporto-sale\/","url":"https:\/\/evolve-fitness.eu\/lt\/projektai\/bigz-sporto-sale\/","name":"\"Bigz\" sporto sal\u0117 - Evolve","isPartOf":{"@id":"https:\/\/evolve-fitness.eu\/lt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/bigz-sporto-sale\/#primaryimage"},"image":{"@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/bigz-sporto-sale\/#primaryimage"},"thumbnailUrl":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz2-scaled.jpg","datePublished":"2026-02-24T12:09:30+00:00","dateModified":"2026-04-22T15:52:15+00:00","description":"\u0160\u012f fitneso STUDIJOS projekt\u0105 Bir\u017euose, Lietuvoje, apr\u016bpinome kruop\u0161\u010diai atrinkta \"Evolve\" komercine treniruokli\u0173 \u012franga.","breadcrumb":{"@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/bigz-sporto-sale\/#breadcrumb"},"inLanguage":"lt-LT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/evolve-fitness.eu\/lt\/projektai\/bigz-sporto-sale\/"]}]},{"@type":"ImageObject","inLanguage":"lt-LT","@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/bigz-sporto-sale\/#primaryimage","url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz2-scaled.jpg","contentUrl":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz2-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/evolve-fitness.eu\/lt\/projektai\/bigz-sporto-sale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/evolve-fitness.eu\/lt\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/evolve-fitness.eu\/lt\/projektai\/"},{"@type":"ListItem","position":3,"name":"&#8220;Bigz&#8221; sporto sal\u0117"}]},{"@type":"WebSite","@id":"https:\/\/evolve-fitness.eu\/lt\/#website","url":"https:\/\/evolve-fitness.eu\/lt\/","name":"Evolve","description":"Your Evolved Gear Arrived","publisher":{"@id":"https:\/\/evolve-fitness.eu\/lt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/evolve-fitness.eu\/lt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"lt-LT"},{"@type":"Organization","@id":"https:\/\/evolve-fitness.eu\/lt\/#organization","name":"Evolve","url":"https:\/\/evolve-fitness.eu\/lt\/","logo":{"@type":"ImageObject","inLanguage":"lt-LT","@id":"https:\/\/evolve-fitness.eu\/lt\/#\/schema\/logo\/image\/","url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/05\/Evolve-logo.svg","contentUrl":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2023\/05\/Evolve-logo.svg","width":176,"height":20,"caption":"Evolve"},"image":{"@id":"https:\/\/evolve-fitness.eu\/lt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EvolveFitnessEurope"]}]}},"featured_image":{"id":232973,"url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz2-1024x768.jpg","full_url":"https:\/\/evolve-fitness.eu\/wp-content\/uploads\/2026\/02\/bigz2-scaled.jpg","alt":"","width":2560,"height":1920},"_links":{"self":[{"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/project\/232971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/media\/232973"}],"wp:attachment":[{"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/media?parent=232971"}],"wp:term":[{"taxonomy":"projects","embeddable":true,"href":"https:\/\/evolve-fitness.eu\/lt\/wp-json\/wp\/v2\/projects?post=232971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}